{"id":381280,"date":"2021-06-08T12:35:59","date_gmt":"2021-06-08T19:35:59","guid":{"rendered":"https:\/\/www.genesys.com\/?page_id=381280"},"modified":"2025-07-22T23:29:08","modified_gmt":"2025-07-23T06:29:08","slug":"retail","status":"publish","type":"page","link":"https:\/\/www.genesys.com\/pt-br\/solutions\/retail","title":{"rendered":"Com\u00e9rcio varejista"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section background_color=&#8221;bgc-lgray&#8221; flair=&#8221;%5B%7B%22hide_mobile%22%3A%22yes%22%7D%5D&#8221; vib=&#8221;enable&#8221; css=&#8221;.vc_custom_1714589368674{background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_row content_placement=&#8221;middle&#8221; vib=&#8221;enable&#8221; vib_top=&#8221;-6.167rem&#8221;][vc_column]<div class=\"component breadcrumbs theme-\"><div class=\"links-row w-100 d-flex flex-wrap align-items-center justify-content-start\"><div class=\"link-col\"><a class=\"breadcrumb-link\" href=\"https:\/\/www.genesys.com\/pt-br\/solutions\">Solu\u00e7\u00f5es<\/a><\/div><\/div><\/div>[\/vc_column][vc_column width=&#8221;5\/12&#8243;][vc_column_text css=&#8221;&#8221;]<\/p>\n<h1>Solu\u00e7\u00f5es de atendimento ao cliente do setor de varejo<\/h1>\n<p class=\"text-22\">Ofere\u00e7a as melhores experi\u00eancias para que os clientes de varejo continuem voltando<\/p>\n<p>[\/vc_column_text]<div class=\"btn-container  \"><a role=\"button\"  class=\"btn btn-primary\" href=\"#demo\" target=\"\" rel=\"\">Come\u00e7ar agora<\/a><a role=\"button\"  class=\"btn btn-ff-primary chevron\" href=\"\/pt-br\/campaign\/request-a-demo\" target=\"\" rel=\"\">Solicite uma demonstra\u00e7\u00e3o<\/a><\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243; offset=&#8221;vc_col-sm-offset-1&#8243;][vc_single_image image=&#8221;568797&#8243; alignment=&#8221;right&#8221; css=&#8221;&#8221; rounded_corners=&#8221;rounded-lg&#8221;][\/vc_column][\/vc_row][\/vc_section][vc_section][vc_row content_placement=&#8221;middle&#8221;][vc_column width=&#8221;1\/2&#8243;]<div class=\"genesys-image play-button\"><a class=\"video-lightbox no-btn-label\" href=\"https:\/\/www.youtube.com\/embed\/-80QB8Qubb8?rel=0\"><img decoding=\"async\" src=\"https:\/\/www.genesys.com\/media\/video_thumb-Imagine_the_future_of_the_customer_journey.png\" alt=\"Video thumb imagine the future of the customer journey\" width=\"823\" height=\"460\" class=\"rounded-xs\"\/><div class=\"video-backdrop\"><\/div><div class=\"play-btn bgc-white rounded d-flex align-items-center justify-content-center\"><div class=\"play-icon d-flex align-items-center justify-content-center\"><i class=\"fa-kit fa-play\"><\/i><\/div><\/div><\/a><\/div>[\/vc_column][vc_column width=&#8221;5\/12&#8243; offset=&#8221;vc_col-sm-offset-1&#8243;][vc_column_text css=&#8221;&#8221;]<\/p>\n<h2>Gere fidelidade com uma experi\u00eancia de compra simples e feita sob medida<\/h2>\n<p>Integre os dados do cliente em cada etapa da jornada para personalizar a experi\u00eancia de forma relevante. Use uma plataforma unificada para oferecer as melhores experi\u00eancias poss\u00edveis, mesmo durante per\u00edodos de pico e em eventos.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section background_color=&#8221;bgc-lgray&#8221; flair=&#8221;%5B%7B%22flair_type%22%3A%22f_type_image%22%2C%22hide_mobile%22%3A%22yes%22%7D%5D&#8221;][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;&#8221;]<\/p>\n<h2>Integre a jornada do cliente a um suporte de varejo \u00e1gil e escal\u00e1vel.<\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221;][vc_column width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]<\/p>\n<h3 class=\"h5\">Ofere\u00e7a a pr\u00f3xima melhor a\u00e7\u00e3o<\/h3>\n<p>Entenda seus clientes, antecipe os pr\u00f3ximos passos e ofere\u00e7a suporte no momento certo, usando a intelig\u00eancia artificial para criar experi\u00eancias mais consistentes.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]<\/p>\n<h3 class=\"h5\">Ofere\u00e7a aos representantes uma plataforma unificada<\/h3>\n<p>Ofere\u00e7a experi\u00eancias flu\u00eddas em todos os canais e sistemas, tudo a partir de uma \u00fanica plataforma.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text css=&#8221;&#8221;]<\/p>\n<h3 class=\"h5\">Conquiste clientes fi\u00e9is e recorrentes<\/h3>\n<p>Analise as jornadas para resolver problemas antes que aconte\u00e7am e entregue uma experi\u00eancia t\u00e3o boa que faz o cliente voltar. [\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section flair=&#8221;%5B%7B%22flair_type%22%3A%22f_type_image%22%2C%22hide_mobile%22%3A%22yes%22%7D%5D&#8221;][vc_row][vc_column width=&#8221;7\/12&#8243;][vc_column_text css=&#8221;&#8221;]<\/p>\n<h2>Leve a experi\u00eancia do cliente al\u00e9m do carrinho e continue encantando mesmo ap\u00f3s a compra.<\/h2>\n<p>A chave para oferecer um servi\u00e7o incr\u00edvel \u00e9 conectar cada momento da jornada do consumidor. A Genesys oferece as solu\u00e7\u00f5es que as empresas de varejo necessitam para atender \u00e0s expectativas em constante evolu\u00e7\u00e3o, tudo a partir de uma plataforma unificada. Escale e inove a qualquer momento, sem arriscar a experi\u00eancia do cliente.[\/vc_column_text][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243; elemental_order=&#8221;order-2&#8243;][vc_column_text ct_style=&#8221;list-block&#8221; css=&#8221;&#8221;]<\/p>\n<h3 class=\"h5\">Preveja as necessidades dos clientes<\/h3>\n<p>Esteja presente onde o cliente quiser e v\u00e1 al\u00e9m do suporte reativo, garantindo uma experi\u00eancia realmente conectada e satisfat\u00f3ria.<\/p>\n<p>Use dados hist\u00f3ricos e em tempo real para prever necessidades e oferecer ao cliente suporte proativo e sem agentes. Atenda aos clientes nos canais que eles preferem e com mensagens com as quais se identifiquem. Use a IA para entregar aos compradores exatamente o que eles precisam, no momento certo.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text ct_style=&#8221;list-block&#8221; css=&#8221;&#8221;]<\/p>\n<h3 class=\"h5\">Engaje os consumidores nos termos deles<\/h3>\n<p>Os clientes querem a liberdade de navegar na jornada de compras por conta pr\u00f3pria. Ofere\u00e7a a eles o poder de entrar em contato com sua marca e encontrar respostas em qualquer canal. E deixe-os fazer tudo isso sem precisar interagir com um agente.<\/p>\n<p>Inclua o autoatendimento, como o WISMO, nas intera\u00e7\u00f5es, identifique quando ele ser\u00e1 \u00fatil e ofere\u00e7a essa op\u00e7\u00e3o antes para evitar contatos desnecess\u00e1rios.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text ct_style=&#8221;list-block&#8221; css=&#8221;&#8221;]<\/p>\n<h3 class=\"h5\">Atenda aos pedidos e \u00e0s expectativas em todos os canais<\/h3>\n<p>Compre, clique, colete. Conecte esses momentos entre canais com conveni\u00eancia. Use a IA para acompanhar jornadas, identificar necessidades e gerar engagement por meio dos canais preferidos.<\/p>\n<p>Facilite o acompanhamento de pedidos e a resolu\u00e7\u00e3o r\u00e1pida de problemas de forma satisfat\u00f3ria para o cliente e para os resultados finais.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text ct_style=&#8221;list-block&#8221; css=&#8221;&#8221;]<\/p>\n<h3 class=\"h5\">Incentive a satisfa\u00e7\u00e3o do cliente e seus resultados<\/h3>\n<p>Promover fidelidade significa conhecer os consumidores. A Genesys possibilita a coleta de dados transacionais e de comportamento do cliente em todos os canais para que voc\u00ea possa entender as necessidades e prefer\u00eancias do cliente em todas as etapas da compra.<\/p>\n<p>Use IA para resolver problemas e oferecer sugest\u00f5es de produtos no momento mais adequado para a venda. Conecte-se com seus clientes de forma proativa para al\u00e9m do ponto de venda com ofertas e engagement automatizados e personalizados.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section flair=&#8221;%5B%7B%22flair_type%22%3A%22f_type_image%22%2C%22flair_image%22%3A%22565280%22%2C%22flair_width%22%3A%22100%25%22%2C%22flair_height%22%3A%22100%25%22%2C%22flair_top%22%3A%2250%25%22%2C%22flair_left%22%3A%220%22%2C%22flair_transform%22%3A%22translateY(-50%25)%22%2C%22flair_classes%22%3A%22object-fit-cover%22%7D%5D&#8221; el_class=&#8221;d-flex align-items-center&#8221;][vc_row r_gutter_size=&#8221;gutter-small&#8221; background_color=&#8221;bgc-glass&#8221; equal_height=&#8221;yes&#8221; el_class=&#8221;py-3 px-1 px-lg-3 rounded mt-0&#8243;][vc_column width=&#8221;7\/12&#8243;][vc_column_text css=&#8221;&#8221;]<\/p>\n<h2>A Genesys tem os recursos para o atendimento ao cliente de varejo<\/h2>\n<p>Os consumidores t\u00eam muitas op\u00e7\u00f5es, especialmente on-line. Para manter as vendas est\u00e1veis e promover a fidelidade, um bom atendimento ao cliente \u00e9 fundamental. Invista em uma solu\u00e7\u00e3o que prioriza IA, cresce com o seu neg\u00f3cio e mant\u00e9m a experi\u00eancia do cliente sempre impec\u00e1vel.[\/vc_column_text][\/vc_column][vc_column el_class=&#8221;mt-2&#8243;][vc_row_inner r_gutter_size=&#8221;gutter-small&#8221; ri_scrollable=&#8221;yes&#8221;][vc_column_inner width=&#8221;1\/3&#8243;]<a class=\"component card w-100 bgc-glass-dark vertical text-start nomedia  chevron-only  \" href=\"\/pt-br\/capabilities\/genesys-ai\" target=\"\" rel=\"\" ><div class=\"card-body\"><h3 class=\"h5\">Intelig\u00eancia artificial (IA)<\/h3>\n<p>Promova experi\u00eancias personalizadas em grande escala com a IA da Genesys Cloud\u2122.<\/p>\n<\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"small mt-0 chevron btn btn-secondary  only\"><\/div><\/div><\/div><\/a>[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<a class=\"component card w-100 bgc-glass-dark vertical text-start nomedia  chevron-only  \" href=\"\/pt-br\/capabilities\/customer-self-service\" target=\"\" rel=\"\" ><div class=\"card-body\"><h3 class=\"h5\">Autoatendimento<\/h3>\n<p>Equipe seus clientes com as ferramentas de autoatendimento de que eles precisam.<\/p>\n<\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"small mt-0 chevron btn btn-secondary  only\"><\/div><\/div><\/div><\/a>[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<a class=\"component card w-100 bgc-glass-dark vertical text-start nomedia  chevron-only  \" href=\"\/pt-br\/capabilities\/automated-routing\" target=\"\" rel=\"\" ><div class=\"card-body\"><h3 class=\"h5\">Roteamento automatizado<\/h3>\n<p>Encaminhe sempre para o agente certo utilizando o poder da IA.<\/p>\n<\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"small mt-0 chevron btn btn-secondary  only\"><\/div><\/div><\/div><\/a>[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<a class=\"component card w-100 bgc-glass-dark vertical text-start nomedia  chevron-only  \" href=\"\/pt-br\/capabilities\/predictive-web-engagement\" target=\"\" rel=\"\" ><div class=\"card-body\"><h3 class=\"h5\">Engagement preditivo na web<\/h3>\n<p>Saiba quem est\u00e1 visitando seu site e ajude a guiar a jornada do comprador at\u00e9 a finaliza\u00e7\u00e3o da compra.<\/p>\n<\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"small mt-0 chevron btn btn-secondary  only\"><\/div><\/div><\/div><\/a>[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<a class=\"component card w-100 bgc-glass-dark vertical text-start nomedia  chevron-only  \" href=\"\/pt-br\/capabilities\/chatbots\" target=\"\" rel=\"\" ><div class=\"card-body\"><h3 class=\"h5\">Agentes virtuais<\/h3>\n<p>Gere engagement com seus clientes usando agentes virtuais com IA, por texto e voz.<\/p>\n<\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"small mt-0 chevron btn btn-secondary  only\"><\/div><\/div><\/div><\/a>[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<a class=\"component card w-100 bgc-glass-dark vertical text-start nomedia  chevron-only  \" href=\"\/pt-br\/capabilities\/call-center-software\" target=\"\" rel=\"\" ><div class=\"card-body\"><h3 class=\"h5\">Software para call center<\/h3>\n<p>Facilite o contato com voc\u00ea por meio do canal preferido por eles.<\/p>\n<\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"small mt-0 chevron btn btn-secondary  only\"><\/div><\/div><\/div><\/a>[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<a class=\"component card w-100 bgc-glass-dark vertical text-start nomedia  chevron-only  \" href=\"\/pt-br\/capabilities\/work-automation-and-task-routing\" target=\"\" rel=\"\" ><div class=\"card-body\"><h3 class=\"h5\">Automa\u00e7\u00e3o do trabalho<\/h3>\n<p>Use dados precisos e consistentes para tomar decis\u00f5es mais informadas em todo o seu back-office.<\/p>\n<\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"small mt-0 chevron btn btn-secondary  only\"><\/div><\/div><\/div><\/a>[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<a class=\"component card w-100 bgc-glass-dark vertical text-start nomedia  chevron-only  \" href=\"\/pt-br\/capabilities\/digital-sales-service-automation\" target=\"\" rel=\"\" ><div class=\"card-body\"><h3 class=\"h5\">Vendas digitais e automa\u00e7\u00e3o de servi\u00e7os<\/h3>\n<p>Reduza custos e crie melhores experi\u00eancias do cliente em todos os canais.<\/p>\n<\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"small mt-0 chevron btn btn-secondary  only\"><\/div><\/div><\/div><\/a>[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<a class=\"component card w-100 bgc-glass-dark vertical text-start nomedia  chevron-only  \" href=\"\/pt-br\/capabilities\/reporting-analytics\" target=\"\" rel=\"\" ><div class=\"card-body\"><h3 class=\"h5\">Relat\u00f3rios e an\u00e1lises<\/h3>\n<p>Obtenha os insights necess\u00e1rios para criar experi\u00eancias mais direcionadas.<\/p>\n<\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"small mt-0 chevron btn btn-secondary  only\"><\/div><\/div><\/div><\/a>[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<a class=\"component card w-100 bgc-glass-dark vertical text-start nomedia  chevron-only  \" href=\"\/pt-br\/capabilities\/social-media-customer-service\" target=\"\" rel=\"\" ><div class=\"card-body\"><h3 class=\"h5\">Redes sociais<\/h3>\n<p>Gere engagement com os clientes nas plataformas que eles j\u00e1 usam por meio do social listening e respostas.<\/p>\n<\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"small mt-0 chevron btn btn-secondary  only\"><\/div><\/div><\/div><\/a>[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<a class=\"component card w-100 bgc-glass-dark vertical text-start nomedia  chevron-only  \" href=\"\/pt-br\/capabilities\/wem-workforce-engagement-management\" target=\"\" rel=\"\" ><div class=\"card-body\"><h3 class=\"h5\">Engagement da for\u00e7a de trabalho<\/h3>\n<p>Atraia os melhores talentos e crie experi\u00eancias mais prazerosas para os colaboradores.<\/p>\n<\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"small mt-0 chevron btn btn-secondary  only\"><\/div><\/div><\/div><\/a>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section background_color=&#8221;bgc-lgray&#8221; flair=&#8221;%5B%7B%22flair_type%22%3A%22f_type_image%22%2C%22hide_mobile%22%3A%22yes%22%7D%5D&#8221;][vc_row equal_height=&#8221;yes&#8221;][vc_column width=&#8221;2\/3&#8243;][vc_column_text css=&#8221;&#8221;]<\/p>\n<h2>Veja por que os clientes do setor de varejo confiam na Genesys<\/h2>\n<p>[\/vc_column_text][\/vc_column][vc_column elemental_order=&#8221;order-5&#8243; offset=&#8221;vc_col-md-4&#8243;]<div class=\"btn-container justify-content-lg-end justify-content-center\"><a role=\"button\"  class=\"btn chevron btn-secondary\" href=\"\/pt-br\/customer-stories\" target=\"\" rel=\"\">Explore mais hist\u00f3rias<\/a><\/div>[\/vc_column][vc_column]<div class=\"component-customer-carousel default-layout single-customer\" data-current-active=\"0\" data-layout=\"default\" data-count=\"1\"><div class=\"carousel-main-row\"><div class=\"carousel-content-col\"><div class=\"customer-content active\" data-href=\"374693\" data-index=\"0\"><a class=\"content-row w-100 bgc-glass\" tabindex=\"-1\" href=\"https:\/\/www.genesys.com\/pt-br\/customer-stories\/techstyleos\"><div class=\"customer-image-col\"><img decoding=\"async\" class=\"header-image\" alt=\"Customer story video thumbnail techstyle\" src=\"https:\/\/www.genesys.com\/media\/customer-story_video-thumbnail_TechStyle.jpg\" width=\"1216\" height=\"684\"><\/div><div class=\"customer-quote-col\"><img decoding=\"async\" class=\"company-logo\" alt=\"\" src=\"https:\/\/www.genesys.com\/media\/TechStyle_OSx250.png\"  width=\"250\" height=\"39\"><p class=\"quote-content mb-2 quote-size-lg\">\u201cO tempo de inatividade costumava ser uma ocorr\u00eancia semanal, mas agora eu nem consigo lembrar quando foi a \u00faltima vez que tivemos um incidente. S\u00f3 em termos de produtividade, acreditamos que economizamos cerca de 2.000 horas.\u201d<\/p><p class=\"customer-name text-18 font-weight-bold mb-0\">Jack Roberts<\/p><p class=\"customer-title\">Diretor, Tecnologia GMS e Aplicativos, TechStyleOS<\/p><div class=\"btn-container\"><div class=\"btn btn-secondary small\">Leia mais<\/div><\/div><\/div><\/a><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section flair=&#8221;%5B%5D&#8221;][vc_row][vc_column]<div class=\"chunk-template-container\" ><div class=\"wpb-content-wrapper\"><p>[vc_section flair=&#8221;%5B%7B%22hide_mobile%22%3A%22yes%22%7D%5D&#8221;][vc_row][vc_column offset=&#8221;vc_col-md-offset-1 vc_col-md-10&#8243;]<a class=\"component-cta-block card w-100 h-100 bgc-lgray centered cta-text-start \"  href=\"\/pt-br\/resources\/state-of-cx-report\" target=\"\" rel=\"\"><div class=\"row align-items-center image-stack card-body\"><div class=\"col-content col-md-6\"><div class=\"content-container\"><h2>Relat\u00f3rio do estado da CX de 2025<\/h2>\n<p class=\"text-20\">Descubra os principais insights de mais de 5.000 consumidores globais e 1.000 l\u00edderes de CX.<\/p>\n<\/div><div class=\" btn-container mt-2\"><div class=\"btn btn-primary\">Baixe agora<\/div><\/div><\/div><div class=\"col-image col-md-6 flex-column justify-content-center mt-1 mt-lg-0 img-top-container no-offset\"><img decoding=\"async\" width=\"820\" height=\"464\" src=\"https:\/\/www.genesys.com\/media\/Resource-thumbnail_State-of-Customer-Experience-2025_1x.png\" alt=\"Access our flagship research report for global insights into the future of CX\" class=\"rounded\"><\/div><\/div><\/a>[\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div><\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section disable_element=&#8221;yes&#8221; flair=&#8221;%5B%7B%22flair_type%22%3A%22f_type_image%22%2C%22hide_mobile%22%3A%22yes%22%7D%5D&#8221;][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;&#8221;]<\/p>\n<h2>Saiba mais sobre como a Genesys pode ajudar os varejistas<\/h2>\n<p>[\/vc_column_text][\/vc_column][vc_column elemental_order=&#8221;order-5&#8243; offset=&#8221;vc_col-md-6&#8243;]<div class=\"btn-container justify-content-lg-end justify-content-center\"><a role=\"button\"  class=\"btn chevron btn-secondary\" href=\"\/pt-br\/resources\" target=\"\" rel=\"\">Conhe\u00e7a todos os recursos<\/a><\/div>[\/vc_column][vc_column][\/vc_column][\/vc_row][\/vc_section][vc_section sec_modern_width=&#8221;enable&#8221; background_color=&#8221;bgc-lgray&#8221; flair=&#8221;%5B%7B%22flair_type%22%3A%22f_type_image%22%2C%22hide_mobile%22%3A%22yes%22%7D%5D&#8221; css=&#8221;.vc_custom_1743403899102{background-image: url(https:\/\/www.genesys.com\/media\/Threads-Right-Wave.png?id=549945) !important;}&#8221; el_class=&#8221;px-0 py-2 px-md-5 py-md-5 mb-5&#8243; el_id=&#8221;demo&#8221;][vc_row background_color=&#8221;bgc-glass&#8221; content_placement=&#8221;middle&#8221; el_class=&#8221;form-card&#8221;][vc_column width=&#8221;5\/12&#8243;][vc_column_text css=&#8221;&#8221;]<\/p>\n<h2>Reformule o software de atendimento ao cliente do varejo<\/h2>\n<p>Conquiste clientes fi\u00e9is por muitos anos. Para atender \u00e0s crescentes expectativas, as marcas devem oferecer experi\u00eancias omnichannel personalizadas. Isso significa conectar dados para entregar experi\u00eancias perfeitas em grande escala. Gere engagement com os clientes por meio desses insights, seja qual for o canal ou local da compra.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243; offset=&#8221;vc_col-sm-offset-1&#8243;]<div class=\"eloq_form elq-container gmkto_form_type_hot gmkto_format_vertical\"><form method=\"post\" name=\"MasterLeadIntakeForm\" action=\"https:\/\/s1260946616.t.eloqua.com\/e\/f2\" data-proc=\"inline\" data-ppcount=\"5\" onsubmit=\"return proc_submit(this);\" class=\"beam-form elq-form init no-bg-form yesknown yesprefill yespp strict-check\"  data-target=\".thank-you\" ><div id=\"known_person\" style=\"display:none;\"><p class=\"welcome_user\"><span id=\"welcome_person\">Welcome back<\/span> <span id=\"person_info\"><span class=\"person_first\"><\/span>&nbsp;<span class=\"person_last\"><\/span><\/span><\/p><p class=\"delete_button\"><a class=\"deletemyrecord\">Not You?<\/a><\/p>\n    <div class=\"form-row cb_available white-box work-email el_field form-floating\">\n        <input type=\"email\" class=\"form-control el_field elq-item-input cb_available  required\" name=\"secondaryEmailAddress1\" id=\"fe644\" value=\"\" placeholder=\"Please provide your work email\">\n        <label for=\"fe644\">Please provide your work email<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div><\/div><input value=\"MasterLeadIntakeForm\" type=\"hidden\" name=\"elqFormName\"><input value=\"1260946616\" type=\"hidden\" name=\"elqSiteId\"><input name=\"elqCampaignId\" type=\"hidden\"><input type=\"hidden\" name=\"elqCustomerGUID\" value=\"\"><input type=\"hidden\" name=\"elqCookieWrite\" value=\"0\"><input type=\"hidden\" name=\"client_ip_address\" id=\"fe449\" value=\"\"><div class=\"fields\"><input type=\"hidden\" name=\"CID\" id=\"fe198\" value=\"7010d000001KeaxAAC\"><input type=\"hidden\" name=\"CID_STATUS\" id=\"fe281\" value=\"\"><input type=\"hidden\" name=\"redirect_url\" id=\"fe217\" value=\"\"><input type=\"hidden\" name=\"landing_page_url\" id=\"fe204\" value=\"https:\/\/www.genesys.com\/pt-br\/wp-json\/wp\/v2\/pages\/381280\"><input type=\"hidden\" name=\"post_type\" id=\"fe448\" value=\"page\"><input type=\"hidden\" name=\"integration\" id=\"fe362\" value=\"\"><input type=\"hidden\" name=\"language_code\" id=\"fe479\" value=\"pt-br\"><input type=\"hidden\" name=\"full_url\" id=\"fe983\" value=\"https:\/\/www.genesys.com\/pt-br\/wp-json\/wp\/v2\/pages\/381280\"><input type=\"hidden\" name=\"post_id\" id=\"fe984\" value=\"381280\">\n    <div class=\"form-row row-email el_field form-floating\">\n        <input type=\"email\" class=\"form-control el_field elq-item-input required\" name=\"emailAddress\" id=\"fe192\" value=\"\" aria-label=\"Email Corporativo\" placeholder=\"Email Corporativo\">\n        <label for=\"fe192\">Email Corporativo<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available el_field form-floating\">\n        <input type=\"text\" class=\"form-control el_field elq-item-input cb_available  required\" name=\"firstName\" id=\"fe190\" value=\"\" placeholder=\"Nome\">\n        <label for=\"fe190\">Nome<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available el_field form-floating\">\n        <input type=\"text\" class=\"form-control el_field elq-item-input cb_available required\" name=\"lastName\" id=\"fe191\" value=\"\" placeholder=\"Sobrenome\">\n        <label for=\"fe191\">Sobrenome<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row form-floating el_field\">\n        <input type=\"tel\" class=\"form-control el_field elq-item-input required pre-exclude\" name=\"busPhone\" id=\"fe215\" value=\"\" placeholder=\"Telefone\">\n        <label for=\"fe215\">Telefone<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe219\" name=\"jobLevel1\" data-value=\"\">\n            <option selected=\"\" value=\"\"><\/option><option value=\"C-Level\">C-Level<\/option><option value=\"VP\">Vice Presidente<\/option><option value=\"Director\">Diretor<\/option><option value=\"Manager\">Gerente<\/option><option value=\"Principal\">Presidente<\/option><option value=\"Engineer \/ Architect\">Engenheiro\/Arquiteto<\/option><option value=\"Consultant\">Consultor<\/option><option value=\"Analyst\">Analista<\/option><option value=\"Partner\">Parceiro<\/option><option value=\"Staff\">Staff<\/option><option value=\"Unknown\">Desconhecida<\/option>\n        <\/select>\n        <label for=\"fe219\">N\u00edvel<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe218\" name=\"jobFunction1\" data-value=\"\">\n            <option selected=\"\" value=\"\"><\/option>\n            <option value=\"Claims\">Seguros<\/option><option value=\"Collections\">Cobran\u00e7as<\/option><option value=\"Contact Center Management\">Gerenciamento de Contact Center<\/option><option value=\"Customer Experience\">Experi\u00eancia do cliente<\/option><option value=\"Customer Service\">Atendimento ao cliente<\/option><option value=\"Ecommerce\/Digital Channels\">Ecommerce\/Canais digitais<\/option><option value=\"Finance\">Finan\u00e7as<\/option><option value=\"Human Resources\">Recursos Humanos<\/option><option value=\"Influencer\">Influenciador<\/option><option value=\"Information Technology\">Tecnologia da Informa\u00e7\u00e3o<\/option><option value=\"IT Architecture\">Arquitetura de TI<\/option><option value=\"IT Infrastructure\">Infraestrutura de TI<\/option><option value=\"IVR\">URA<\/option><option value=\"Marketing\">Marketing<\/option><option value=\"Operations \/ Process Management\">Opera\u00e7\u00f5es\/Gerenciamento de Processos<\/option><option value=\"Production Management\">Gerenciamento de Produ\u00e7\u00e3o<\/option><option value=\"Purchasing\">Compras<\/option><option value=\"Sales\">Vendas<\/option><option value=\"Unknown\">Desconhecida<\/option>\n        <\/select>\n        <label for=\"fe218\">Fun\u00e7\u00e3o<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <input type=\"text\" class=\"form-control el_field elq-item-input cb_available required eloq_ppe\" name=\"company\" id=\"fe193\" value=\"\" placeholder=\"Empresa\">\n        <label for=\"fe193\">Empresa<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe194\" name=\"country\" data-value=\"\">\n            <option value=\"\"><\/option>\n            <!-- Add country options here -->\n        <\/select>\n        <label for=\"fe194\">Pa\u00eds<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available country_dep el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe214\" name=\"stateProv\" data-value=\"\">\n            <option selected=\"\" value=\"\"><\/option>\n        <\/select>\n        <label for=\"fe214\">Estado<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <input type=\"text\" class=\"form-control el_field elq-item-input cb_available required eloq_ppe\" name=\"website1\" id=\"fe801\" value=\"\" placeholder=\"Your Website\">\n        <label for=\"fe801\">Your Website<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <input type=\"text\" class=\"form-control el_field elq-item-input cb_available required eloq_ppe\" name=\"city\" id=\"fe226\" value=\"\" placeholder=\"Cidade\">\n        <label for=\"fe226\">Cidade<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <input type=\"text\" class=\"form-control el_field elq-item-input cb_available required eloq_ppe\" name=\"title\" id=\"fe220\" value=\"\" placeholder=\"Cargo\">\n        <label for=\"fe220\">Cargo<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe221\" name=\"industry1\" data-value=\"\">\n            <option value=\"\" ><\/option>\n            <option value=\"Banking\">Servi\u00e7os banc\u00e1rios<\/option><option value=\"Business Services\">Presta\u00e7\u00e3o de servi\u00e7os a empresas<\/option><option value=\"Capital Markets\">Mercado de Capitais<\/option><option value=\"Communications\">Ag\u00eancia de Comunica\u00e7\u00e3o<\/option><option value=\"Consumer Products\">Bens de Consumo<\/option><option value=\"Defense & Intelligence\">Defesa & Intelig\u00eancia<\/option><option value=\"Education & Non-Profit\">Educa\u00e7\u00e3o<\/option><option value=\"Energy & Utilities\">Energia & Utilities<\/option><option value=\"Entertainment\">Entretenimento<\/option><option value=\"Government\">Governo<\/option><option value=\"Insurance\">Seguros<\/option><option value=\"Life Sciences\">Bioci\u00eancia<\/option><option value=\"Logistics\">Log\u00edstica<\/option><option value=\"Manufacturing\">Manufacturing<\/option><option value=\"Payors\">Payors<\/option><option value=\"Providers\">Provedores<\/option><option value=\"Retailers\">Varejo<\/option><option value=\"Technology\">Tecnologia<\/option><option value=\"Travel & Hospitality\">Viagem & Hospedagem<\/option><option value=\"Retail Banking\">Banco de Varejo<\/option><option value=\"Other\">Outro<\/option>\n        <\/select>\n        <label for=\"fe221\">Ind\u00fastria<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe222\" name=\"levelofInterest1\" data-value=\"\">\n            <option value=\"\"><\/option>\n            <option value=\"Just researching\">Apenas pesquisando<\/option><option value=\"Gathering business requirements\">Consolidando requisitos de neg\u00f3cios<\/option><option value=\"Comparing solutions\">Comparando solu\u00e7\u00f5es<\/option><option value=\"Ready for a conversation\">Pronto para uma conversa<\/option>\n        <\/select>\n        <label for=\"fe222\">N\u00edvel de Interesse<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe225\" name=\"numberofAgentsForm1\" data-value=\"\">\n            <option value=\"\"><\/option>\n            <option value=\"1-20\">Entre 1 e 20<\/option><option value=\"21-50\">De 21 a 50<\/option><option value=\"51-100\">De 51 a 100<\/option><option value=\"101-300\">De 101 a 300<\/option><option value=\"301-500\">De 301 a 500<\/option><option value=\"501-1000\">De 501 a 1.000<\/option><option value=\">1000\">&gt;1000<\/option><option value=\"No Contact Center\">Sem contact center<\/option><option value=\"Don't Know\">N\u00e3o sei<\/option>\n        <\/select>\n        <label for=\"fe225\">N\u00famero de posi\u00e7\u00f5es de agentes<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div><div class=\"form-check single-checkbox-row form-row gdpr-field white-box \"><input type=\"checkbox\" class=\"el_field eloq_ppe\" name=\"explicitConsentEmailPhone\" id=\"fe224\" val=\"\"><label class=\"checkbox-aligned elq-item-label\" for=\"fe224\">Sim. Gostaria de receber informa\u00e7\u00e3o sobre a Genesys via e-mail ou telefone.<\/label><\/div><div class=\"single-checkbox-row form-row white-box \"><input type=\"checkbox\" class=\"el_field eloq_ppe\" name=\"contactMe\" id=\"fe509\" val=\"\"><label class=\"checkbox-aligned elq-item-label\" for=\"fe509\">Gostaria de ser contatado por um especialista do CX.<\/label><\/div><input type=\"hidden\" data-query=\"utm_medium\" name=\"utm_medium\" id=\"fe199\" value=\"\"><input type=\"hidden\" data-query=\"utm_source\" name=\"utm_source\" id=\"fe200\" value=\"\"><input type=\"hidden\" data-query=\"utm_campaign\" name=\"utm_campaign\" id=\"fe201\" value=\"\"><input type=\"hidden\" data-query=\"utm_term\" name=\"utm_term\" id=\"fe202\" value=\"\"><input type=\"hidden\" data-query=\"utm_content\" name=\"utm_content\" id=\"fe203\" value=\"\"><input type=\"hidden\" data-query=\"ost_tool\" name=\"ost_tool\" id=\"fe293\" value=\"\"><input type=\"hidden\" data-query=\"ost_campaign\" name=\"ost_campaign\" id=\"fe294\" value=\"\"><input type=\"hidden\" data-query=\"ost_content\" name=\"ost_content\" id=\"fe295\" value=\"\"><input type=\"hidden\" data-query=\"blaid\" name=\"eloquaBLAID_c\" id=\"fe3099\" value=\"\"><input type=\"hidden\" data-query=\"gclid\" name=\"gCLID1\" id=\"fe283\" value=\"\"><input type=\"hidden\" data-query=\"mkwid\" name=\"mKWID1\" id=\"fe678\" value=\"\"><input type=\"hidden\" name=\"gAClientID1\" id=\"fe284\" value=\"\"><input type=\"hidden\" name=\"noteCreatorTitle1\" id=\"fe313\" value=\"\"><input type=\"hidden\" name=\"webContentAutoResponderDefault\" id=\"fe286\" value=\"Hot Lead\"><input type=\"hidden\" name=\"webContentAutoResponderTitle\" id=\"fe287\" value=\"\"><input type=\"hidden\" name=\"webContentAutoResponderURL\" id=\"fe288\" value=\"\"><input type=\"hidden\" name=\"noteCreator2\" id=\"fe478\" value=\"\"><input type=\"hidden\" class=\"yesprefill\" name=\"neverbounceResult1\" id=\"fe640\" value=\"OFF\"><input type=\"hidden\" class=\"yesprefill\" name=\"neverbounceFlags1\" id=\"fe641\" value=\"OFF\"><input type=\"hidden\" class=\"yesprefill\" name=\"neverbounceSuggestedCorrection1\" id=\"fe642\" value=\"6sense\"><input type=\"hidden\" name=\"clearbitPersonID1\" id=\"fe630\" value=\"\"><input type=\"hidden\" name=\"clearbitFieldCount1\" id=\"fe633\" value=\"\"><input type=\"hidden\" name=\"clearbitTitle1\" id=\"fe646\" value=\"\"><input type=\"hidden\" name=\"clearbitRole1\" id=\"fe631\" value=\"\"><input type=\"hidden\" name=\"clearbitNumberofEmployees1\" id=\"fe647\" value=\"\"><input type=\"hidden\" name=\"clearbitNumberofEmployeesRange1\" id=\"fe648\" value=\"\"><input type=\"hidden\" name=\"clearbitWebsite1\" id=\"fe802\" value=\"\"><input type=\"hidden\" name=\"browserUserAgent\" id=\"fe3319\" value=\"\"><input type=\"text\" class=\"honeypp\" name=\"honeypp\" id=\"honeypp\" value=\"\" ><input role=\"button\" aria-label=\"Solicite uma demonstra\u00e7\u00e3o\" type=\"Submit\" class=\"submit-button-style btn btn-primary \" value=\"Solicite uma demonstra\u00e7\u00e3o\" id=\"fe195\"><div class=\"loading\"><\/div><div class=\"gdpr-field form-row white-box legal\"><span>By providing your information, you agree to our <a href=\"https:\/\/www.genesys.com\/company\/legal\/privacy-policy\" target=\"_blank\">privacy policy<\/a>.<\/span><\/div><\/div><\/form><\/div>[vc_column_text css=&#8221;&#8221; el_class=&#8221;thank-you&#8221;]<\/p>\n<p class=\"h4\">Obrigado pelo seu interesse.<\/p>\n<p>Entraremos em contato com voc\u00ea para agendar o dia e o hor\u00e1rio mais conveniente.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section][vc_row][vc_column width=&#8221;5\/12&#8243;][vc_column_text css=&#8221;&#8221;]<\/p>\n<h2>Perguntas frequentes sobre atendimento ao cliente do setor de varejo<\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;5\/6&#8243; offset=&#8221;vc_col-sm-offset-1&#8243;]<div class=\"component-accordion-container no-title\" data-display=\"accordion\"><div class=\"component-accordion-content custom-accordion\" data-opened=\"3\"><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Quais s\u00e3o os recursos essenciais do software de atendimento ao cliente para o setor de varejo?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>H\u00e1 uma grande variedade de coisas que o seu software de atendimento ao cliente deve ser capaz de fazer para ajudar a oferecer melhores experi\u00eancias de compras, mas aqui est\u00e3o alguns exemplos:<\/p>\n<ul>\n<li>Engagements de &#8220;pr\u00f3xima melhor a\u00e7\u00e3o&#8221; conduzidos por IA preditiva baseados no momento, bem como no hist\u00f3rico do comportamento e das prefer\u00eancias<\/li>\n<li>Uma vis\u00e3o omnichannel dos clientes que une o comportamento on-line\/off-line para um alcance hiperpersonalizado orientado por IA<\/li>\n<li>An\u00e1lise da jornada do cliente ao longo da jornada de compra e em todos os canais<\/li>\n<li>Automa\u00e7\u00e3o de processos<\/li>\n<\/ul>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Como um software de atendimento ao cliente melhora a fidelidade do cliente?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>N\u00e3o d\u00e1 para subestimar a import\u00e2ncia do atendimento ao cliente. De acordo com a <a href=\"https:\/\/www.genesys.com\/pt-br\/resources\/state-of-cx\">pesquisa da Genesys<\/a>, 30% dos consumidores afirmam ter parado de fazer neg\u00f3cios com alguma empresa ap\u00f3s uma intera\u00e7\u00e3o negativa de atendimento ao cliente. O software de atendimento ao cliente melhora a qualidade do atendimento, reduzindo os erros que podem levar \u00e0 perda de um cliente.<\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Os pequenos varejistas podem se beneficiar de um software de atendimento ao cliente de alta tecnologia?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Sim, qualquer varejista pode se beneficiar do uso de um software de atendimento ao cliente. Para um pequeno varejista, melhorar o atendimento ao cliente \u00e9 ainda mais crucial do que para um grande, porque perder um cliente pesa muito mais. Com uma equipe de suporte menor, os benef\u00edcios da IA e do autoatendimento automatizado s\u00e3o ainda maiores, deixando os agentes humanos que est\u00e3o dispon\u00edveis prontos para os desafios maiores e mais complexos que exigem encaminhamento.<\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Como treinar a equipe para usar novos softwares de atendimento ao cliente de forma eficaz?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Uma das coisas mais importantes que voc\u00ea pode fazer no processo de treinamento \u00e9 obter ades\u00e3o da equipe de atendimento ao cliente. Eles precisam entender que um software de atendimento ao cliente, especialmente com op\u00e7\u00f5es de autoatendimento usando automa\u00e7\u00e3o e IA, \u00e9 uma ferramenta que facilita o trabalho deles, e n\u00e3o um substituto.<\/p>\n<p>Quanto a realmente ensinar os agentes a usar o software, seu fornecedor deve ter uma equipe de sucesso do cliente que possa ajudar. De qualquer forma, envolver os agentes no processo de demonstra\u00e7\u00e3o e avalia\u00e7\u00e3o pode ser \u00fatil, pois d\u00e1 a eles tempo para usar o novo software enquanto h\u00e1 uma rede de seguran\u00e7a em vigor.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div>[\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_section background_color=&#8221;bgc-lgray&#8221; flair=&#8221;%5B%7B%22hide_mobile%22%3A%22yes%22%7D%5D&#8221; vib=&#8221;enable&#8221; css=&#8221;.vc_custom_1714589368674{background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_row content_placement=&#8221;middle&#8221; vib=&#8221;enable&#8221; vib_top=&#8221;-6.167rem&#8221;][vc_column][\/vc_column][vc_column width=&#8221;5\/12&#8243;][vc_column_text css=&#8221;&#8221;] Solu\u00e7\u00f5es de atendimento ao cliente do setor de varejo Ofere\u00e7a as melhores experi\u00eancias para que os clientes de varejo continuem voltando [\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243; offset=&#8221;vc_col-sm-offset-1&#8243;][vc_single_image image=&#8221;568797&#8243; alignment=&#8221;right&#8221; css=&#8221;&#8221; rounded_corners=&#8221;rounded-lg&#8221;][\/vc_column][\/vc_row][\/vc_section][vc_section][vc_row content_placement=&#8221;middle&#8221;][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;5\/12&#8243; offset=&#8221;vc_col-sm-offset-1&#8243;][vc_column_text css=&#8221;&#8221;] Gere fidelidade com uma experi\u00eancia de [&hellip;]<\/p>\n","protected":false},"author":1062,"featured_media":0,"parent":104856,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-381280","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.genesys.com\/pt-br\/wp-json\/wp\/v2\/pages\/381280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.genesys.com\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.genesys.com\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.genesys.com\/pt-br\/wp-json\/wp\/v2\/users\/1062"}],"replies":[{"embeddable":true,"href":"https:\/\/www.genesys.com\/pt-br\/wp-json\/wp\/v2\/comments?post=381280"}],"version-history":[{"count":13,"href":"https:\/\/www.genesys.com\/pt-br\/wp-json\/wp\/v2\/pages\/381280\/revisions"}],"predecessor-version":[{"id":584738,"href":"https:\/\/www.genesys.com\/pt-br\/wp-json\/wp\/v2\/pages\/381280\/revisions\/584738"}],"up":[{"embeddable":true,"href":"https:\/\/www.genesys.com\/pt-br\/wp-json\/wp\/v2\/pages\/104856"}],"wp:attachment":[{"href":"https:\/\/www.genesys.com\/pt-br\/wp-json\/wp\/v2\/media?parent=381280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}