{"id":626008,"date":"2026-05-04T12:52:36","date_gmt":"2026-05-04T19:52:36","guid":{"rendered":"https:\/\/www.genesys.com\/capabilities\/whatsapp"},"modified":"2026-05-27T16:44:20","modified_gmt":"2026-05-27T23:44:20","slug":"whatsapp","status":"publish","type":"capabilities","link":"https:\/\/www.genesys.com\/de-de\/capabilities\/whatsapp","title":{"rendered":"WhatsApp"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section background_color=&#8220;bgc-lgray&#8220; flair=&#8220;%5B%7B%7D%5D&#8220; vib=&#8220;enable&#8220; css=&#8220;.vc_custom_1714410887619{background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8220;][vc_row content_placement=&#8220;middle&#8220; vib=&#8220;enable&#8220; vib_top=&#8220;6.333rem&#8220;][vc_column]<div class=\"component breadcrumbs theme-\"><div class=\"links-row w-100 d-flex flex-wrap align-items-center justify-content-start\"><div class=\"link-col\"><a class=\"breadcrumb-link\" href=\"https:\/\/www.genesys.com\/de-de\/genesys-cloud\">Genesys Cloud CX<\/a><\/div><\/div><\/div>[\/vc_column][vc_column width=&#8220;5\/12&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h1>WhatsApp-Integration in Genesys Cloud f\u00fcr Unternehmen<\/h1>\n<p class=\"text-22\">KI-gest\u00fctzter Messaging- und Anruf-Service f\u00fcr Unternehmen, direkt in WhatsApp<\/p>\n<p>[\/vc_column_text]<div class=\"btn-container  \"><a role=\"button\"  class=\"btn btn-primary\" href=\"#demo\" target=\"\" rel=\"\">Jetzt loslegen<\/a><a role=\"button\"  class=\"btn btn-ff-primary chevron video-lightbox\" href=\"https:\/\/www.youtube.com\/embed\/W_Uj58EhUsg\" target=\"\" rel=\"\">So funktioniert's<\/a><\/div>[\/vc_column][vc_column width=&#8220;1\/2&#8243; offset=&#8220;vc_col-lg-offset-1 vc_col-md-offset-1 vc_col-sm-offset-0&#8243;]<div class=\"genesys-image\"><a class=\"video-lightbox\" href=\"https:\/\/www.youtube.com\/embed\/W_Uj58EhUsg\"><img decoding=\"async\" src=\"https:\/\/www.genesys.com\/media\/Genesys-WhatsApp.jpg\" alt=\"Genesys   whatsapp\" width=\"820\" height=\"464\" class=\"rounded-xs\"\/><\/a><\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section background_color=&#8220;bgc-lgray&#8220; flair=&#8220;%5B%7B%22flair_type%22%3A%22f_type_image%22%2C%22hide_mobile%22%3A%22yes%22%7D%5D&#8220;][vc_row][vc_column width=&#8220;7\/12&#8243; offset=&#8220;vc_col-md-offset-0 vc_col-sm-offset-0&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h2>Bieten Sie eine skalierbare, vernetzte WhatsApp-Erfahrung mit KI-gest\u00fctzter Orchestrierung und Automatisierung<\/h2>\n<p>Genesys Cloud erm\u00f6glicht es Unternehmen, \u00fcber WhatsApp mit Kunden in Kontakt zu treten und verschiedene Messaging-Kan\u00e4le auf einer einzigen Plattform zu vereinen, um Kunden ein ganzheitliches Kommunikationserlebnis zu bieten. Dank agentischer Orchestrierung k\u00f6nnen Unternehmen unzusammenh\u00e4ngende Kundeninteraktionen durch konsistente, vernetzte und personalisierte Customer Journeys ersetzen.<br \/>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row equal_height=&#8220;yes&#8220; el_class=&#8220;hide-shit&#8220;][vc_column width=&#8220;1\/3&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Intelligentes Engagement gezielt f\u00f6rdern<\/h3>\n<p>Nutzen Sie virtuelle Agenten mit Absichtserkennung, um Ma\u00dfnahmen einzuleiten und Kunden durch personalisierte, automatisierte Journeys zu begleiten.[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/3&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Alle Interaktionen an zentraler Stelle b\u00fcndeln<\/h3>\n<p>Verwalten Sie die WhatsApp-Kundenkommunikation mit Sprach-, E-Mail- und Chat-Funktionen in einem zentralen Arbeitsbereich, der eine einheitliche Kundenansicht bietet.[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/3&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Kommunikation mit Zuversicht skalieren<\/h3>\n<p>Erm\u00f6glichen Sie proaktives, regelkonformes und umfassendes Kundenengagement mithilfe von Kampagnen, Automatisierung und Entscheidungsfindung in Echtzeit.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section][vc_row][vc_column width=&#8220;1\/2&#8243;][vc_single_image image=&#8220;631778&#8243; css=&#8220;&#8220; rounded_corners=&#8220;rounded&#8220;][\/vc_column][vc_column width=&#8220;5\/12&#8243; offset=&#8220;vc_col-sm-offset-1&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h2>Nahtlose End-to-End-Konversationen auf WhatsApp orchestrieren<\/h2>\n<p>Lassen Sie fragmentierte Interaktionen hinter sich und bieten Sie durchg\u00e4ngige Customer Journeys, in denen Automatisierung, KI und menschliche Unterst\u00fctzung innerhalb derselben WhatsApp-Konversation vereint sind.[\/vc_column_text][vc_row_inner equal_height=&#8220;yes&#8220; el_class=&#8220;mt-2&#8243;][vc_column_inner][vc_column_text css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Messaging-Konversationen in verschiedensten Formaten f\u00fchren<\/h3>\n<p>\u00dcberzeugen Sie Kunden mit Multimedia-Messaging, das Bilder, Dokumente, Karussell-Pr\u00e4sentationen, interaktive Listen und Call-to-Action-Buttons einschlie\u00dft.[\/vc_column_text][\/vc_column_inner][vc_column_inner][vc_column_text ct_style=&#8220;list-block&#8220; css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Messaging um Spracheingaben erweitern<\/h3>\n<p>Bieten Sie die M\u00f6glichkeit von Sprachnachrichten und einen nahtlosen \u00dcbergang zu Live-Sprachkonversationen durch Business Calling, wobei der Kontext \u00fcber verschiedene Kundeninteraktionen hinweg stets gewahrt bleibt.[\/vc_column_text][\/vc_column_inner][vc_column_inner][vc_column_text ct_style=&#8220;list-block&#8220; css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Einen einheitlichen Arbeitsbereich schaffen<\/h3>\n<p>Vereinen Sie alle WhatsApp-Konversationen auf einer zentralen Plattform und Oberfl\u00e4che, sodass Mitarbeiter s\u00e4mtliche Kundensupport-Interaktionen mit intaktem Kontext und vollst\u00e4ndiger Transparenz handhaben k\u00f6nnen.[\/vc_column_text][\/vc_column_inner][vc_column_inner][vc_column_text ct_style=&#8220;list-block&#8220; css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Proaktives Engagement f\u00f6rdern<\/h3>\n<p>Erreichen Sie Kunden mit ausgehenden Benachrichtigungen, Erinnerungen und Updates unter Verwendung von Nachrichtenvorlagen, Kampagnen und automatisierten Triggern sowie der Verwaltung von Vor- und Nachkontaktregeln.[\/vc_column_text][\/vc_column_inner][vc_column_inner][vc_column_text ct_style=&#8220;list-block&#8220; css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">KI-gest\u00fctzten Self-Service skalieren<\/h3>\n<p>Setzen Sie virtuelle Agenten und Chatbot-Automatisierung ein, um eine autonome L\u00f6sung von Kundenproblemen zu erm\u00f6glichen, dank der Reaktionszeiten verk\u00fcrzt und Mitarbeiter entlastet werden.[\/vc_column_text][\/vc_column_inner][vc_column_inner][vc_column_text ct_style=&#8220;list-block&#8220; css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Betriebliche Effizienz verbessern<\/h3>\n<p>Schaffen Sie isolierte Systeme ab und optimieren Sie den Betrieb durch Unternehmens-, CRM- und API-Integrationen, um eine ganzheitliche Sicht auf die Customer Journey zu erhalten.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section disable_element=&#8220;yes&#8220; flair=&#8220;%5B%7B%22flair_type%22%3A%22f_type_image%22%7D%5D&#8220;][vc_row][vc_column width=&#8220;1\/3&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h2>Nahtlose End-to-End-Konversationen auf WhatsApp orchestrieren<\/h2>\n<p>Lassen Sie fragmentierte Interaktionen hinter sich und bieten Sie durchg\u00e4ngige Customer Journeys, in denen Automatisierung, KI und menschliche Unterst\u00fctzung innerhalb derselben WhatsApp-Konversation vereint sind.[\/vc_column_text][\/vc_column][vc_column width=&#8220;7\/12&#8243; offset=&#8220;vc_col-sm-offset-1&#8243;][vc_row_inner r_gutter_size=&#8220;gutter-small&#8220; ri_scrollable=&#8220;yes&#8220; equal_height=&#8220;yes&#8220;][vc_column_inner width=&#8220;1\/2&#8243;]<div class=\"component card w-100 bgc-lgray vertical text-start nomedia  chevron-only  \" ><div class=\"card-body\"><h3 class=\"h5\">Messaging-Konversationen in verschiedensten Formaten f\u00fchren<\/h3>\n<p>\u00dcberzeugen Sie Kunden mit Multimedia-Messaging, das Bilder, Dokumente, Karussell-Pr\u00e4sentationen, interaktive Listen und Call-to-Action-Buttons einschlie\u00dft.<\/p>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;]<div class=\"component card w-100 bgc-lgray vertical text-start nomedia  chevron-only  \" ><div class=\"card-body\"><h3 class=\"h5\">Messaging um Spracheingaben erweitern<\/h3>\n<p>Bieten Sie die M\u00f6glichkeit von Sprachnachrichten und einen nahtlosen \u00dcbergang zu Live-Sprachkonversationen durch Business Calling, wobei der Kontext \u00fcber verschiedene Kundeninteraktionen hinweg stets gewahrt bleibt.<\/p>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;]<div class=\"component card w-100 bgc-lgray vertical text-start nomedia  chevron-only  \" ><div class=\"card-body\"><h3 class=\"h5\">Einen einheitlichen Arbeitsbereich schaffen<\/h3>\n<p>Vereinen Sie alle WhatsApp-Konversationen auf einer zentralen Plattform und Oberfl\u00e4che, sodass Mitarbeiter s\u00e4mtliche Kundensupport-Interaktionen mit intaktem Kontext und vollst\u00e4ndiger Transparenz handhaben k\u00f6nnen.<\/p>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;]<div class=\"component card w-100 bgc-lgray vertical text-start nomedia  chevron-only  \" ><div class=\"card-body\"><h3 class=\"h5\">Proaktives Engagement f\u00f6rdern<\/h3>\n<p>Erreichen Sie Kunden mit ausgehenden Benachrichtigungen, Erinnerungen und Updates unter Verwendung von Nachrichtenvorlagen, Kampagnen und automatisierten Triggern sowie der Verwaltung von Vor- und Nachkontaktregeln.<\/p>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;]<a class=\"component card w-100 bgc-lgray vertical text-start nomedia  chevron-only  \" href=\"de-de\/capabilities\/virtual-agents\" target=\"\" rel=\"\" ><div class=\"card-body\"><h3 class=\"h5\">KI-gest\u00fctzten Self-Service skalieren<\/h3>\n<p>Setzen Sie virtuelle Agenten und Chatbot-Automatisierung ein, um eine autonome L\u00f6sung von Kundenproblemen zu erm\u00f6glichen, dank der Reaktionszeiten verk\u00fcrzt und Mitarbeiter entlastet werden.<\/p>\n<\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"small mt-0 chevron btn btn-secondary  only\"><\/div><\/div><\/div><\/a>[\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;]<div class=\"component card w-100 bgc-lgray vertical text-start nomedia  chevron-only  \" ><div class=\"card-body\"><h3 class=\"h5\">Betriebliche Effizienz verbessern<\/h3>\n<p>Schaffen Sie isolierte Systeme ab und optimieren Sie den Betrieb durch Unternehmens-, CRM- und API-Integrationen, um eine ganzheitliche Sicht auf die Customer Journey zu erhalten.<\/p>\n<\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section sec_modern_width=&#8220;enable&#8220; background_color=&#8220;bgc-lgray&#8220; flair=&#8220;%5B%7B%22flair_type%22%3A%22f_type_image%22%7D%5D&#8220;][vc_row][vc_column width=&#8220;1\/2&#8243;][vc_column_text ct_style=&#8220;stat&#8220; css=&#8220;&#8220; ct_stat_link=&#8220;url:https%3A%2F%2Fwww.genesys.com%2Fde-de%2Fresources%2Fstate-of-cx|title:%22State%20of%20Customer%20Experience%2C%22%20Genesys%2C%202025&#8243;]<\/p>\n<p class=\"text-60\">86\u00a0%<\/p>\n<p><span style=\"font-weight: 300;\">der CX-F\u00fchrungskr\u00e4fte planen, bis 2027 Messaging-Apps einzuf\u00fchren, wobei 63\u00a0% dies bereits tun<\/span>[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/2&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h2>Messaging ist der neue Kundenkontakt<\/h2>\n<p>Marken entgeht nicht die zunehmende Bedeutung von Plattformen wie WhatsApp f\u00fcr die F\u00f6rderung von Interaktionen auf Kan\u00e4len, die Kunden bereits t\u00e4glich nutzen. Sie erm\u00f6glichen schnellere Antworten, personalisiertere Interaktionen und nahtlose Journeys, die zu h\u00f6heren Konversionsraten, h\u00f6heren CSAT-Werten und reduzierten Servicekosten f\u00fchren.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section][vc_row][vc_column width=&#8220;1\/2&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h3>Mit Genesys differenzierte WhatsApp-Erlebnisse bieten<\/h3>\n<p>Genesys Cloud kombiniert eine native Integration in die WhatsApp Business Platform mit KI-gest\u00fctzten Kundeninteraktionen, die das Business Messaging mit Sprach-, E-Mail- und Chat-Funktionen auf einer zentralen Plattform vereint. Dadurch werden Echtzeit-Entscheidungsfindung, Absichtserkennung und eine nahtlose \u00dcbergabe an menschliche Mitarbeiter erm\u00f6glicht.[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/2&#8243;][vc_row_inner r_gutter_size=&#8220;gutter-small&#8220;][vc_column_inner width=&#8220;1\/2&#8243;][vc_column_text ct_style=&#8220;list-block&#8220; css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5 text-graphite\">Native Integration statt optionales Extra<\/h3>\n<p>WhatsApp Business ist direkt in Genesys Cloud integriert und erm\u00f6glicht einheitliche Journeys anstelle von unzusammenh\u00e4ngenden Interaktionen.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;][vc_column_text ct_style=&#8220;list-block&#8220; css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5 text-graphite\">KI mit greifbaren Ergebnissen<\/h3>\n<p>Agentische virtuelle Agenten verstehen die Absicht, ergreifen Ma\u00dfnahmen und l\u00f6sen Probleme, anstatt lediglich auf Anfragen zu antworten.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;][vc_column_text ct_style=&#8220;list-block&#8220; css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Omnichannel-Orchestrierung mit Hand und Fu\u00df<\/h3>\n<p>Erm\u00f6glichen Sie kanal\u00fcbergreifende Kommunikation, die Messaging-, Sprach- und digitale Kan\u00e4le in einer einzigen, kontinuierlichen Journey einschlie\u00dft.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;][vc_column_text ct_style=&#8220;list-block&#8220; css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5 text-graphite\">Sprache und Text vereint<\/h3>\n<p>Nutzen Sie Business Calling und Sprachnachrichten direkt innerhalb von WhatsApp-Konversationen.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;][vc_column_text ct_style=&#8220;list-block&#8220; css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Unternehmensgerechte Interaktionen<\/h3>\n<p>F\u00fchren Sie umfassende Messaging-Kampagnen mit der Compliance und Sicherheit durch, die von Unternehmen vorausgesetzt werden.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section background_color=&#8220;bgc-lgray&#8220; flair=&#8220;%5B%7B%22flair_type%22%3A%22f_type_image%22%2C%22hide_mobile%22%3A%22yes%22%7D%5D&#8220;][vc_row equal_height=&#8220;yes&#8220;][vc_column width=&#8220;2\/3&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h2>Das sagen unsere Kunden<\/h2>\n<p>[\/vc_column_text][\/vc_column][vc_column elemental_order=&#8220;order-5&#8243; offset=&#8220;vc_col-md-4&#8243;]<div class=\"btn-container justify-content-lg-end justify-content-center\"><a role=\"button\"  class=\"btn chevron btn-secondary\" href=\"\/de-de\/customer-stories\" target=\"\" rel=\"\">Alle Erfolgsgeschichten lesen<\/a><\/div>[\/vc_column][vc_column]<div class=\"component-customer-carousel default-layout\" data-current-active=\"0\" data-layout=\"default\" data-count=\"2\"><div class=\"carousel-main-row\"><div class=\"carousel-logo-col\"><div class=\"logo-nav-item active\"><a class=\"logo-nav\" aria-label=\"View Oldenburgische Landesbank (OLB) story\" title=\"Oldenburgische Landesbank (OLB)\" href=\"#597722\"><img decoding=\"async\" class=\"company-logo\" alt=\"Olb logo\" src=\"https:\/\/www.genesys.com\/media\/OLB-Logo.png\" width=\"960\" height=\"361\"><\/a><\/div><div class=\"logo-nav-item\"><a class=\"logo-nav\" aria-label=\"View Dental Axess story\" title=\"Dental Axess\" href=\"#379751\"><img decoding=\"async\" class=\"company-logo\" alt=\"Dental axess logo\" src=\"https:\/\/www.genesys.com\/media\/Dental-Axess-logo.png\" width=\"300\" height=\"120\"><\/a><\/div><\/div><div class=\"carousel-content-col\"><button aria-label=\"Previous panel\" title=\"Previous panel\" class=\"prev-control carousel-controls hidden\"><\/button><div class=\"customer-content active\" data-href=\"597722\" data-index=\"0\"><a class=\"content-row w-100 bgc-glass\" tabindex=\"-1\" href=\"https:\/\/www.genesys.com\/de-de\/customer-stories\/oldenburgische-landesbank-olb\"><div class=\"customer-image-col\"><img decoding=\"async\" class=\"header-image\" alt=\"Happy couple banking together online.\" src=\"https:\/\/www.genesys.com\/media\/OLB-hero-image.png\" width=\"1088\" height=\"612\"><\/div><div class=\"customer-quote-col\"><p class=\"quote-content mb-2 quote-size-lg\">\u201e\u00dcber WhatsApp k\u00f6nnen unsere Kunden jederzeit direkt von ihrem Telefon aus Kontakt mit uns aufnehmen [...] Es ist bequem und erf\u00fcllt die heutigen Erwartungen von Kunden.\u201c<\/p><p class=\"customer-name text-18 font-weight-bold mb-0\">Felix Leshoff<\/p><p class=\"customer-title\">Senior Associate, Central and Digital Sales<\/p><div class=\"btn-container\"><div class=\"btn btn-secondary small\">Kundenbericht lesen<\/div><\/div><\/div><\/a><\/div><div class=\"customer-content\" data-href=\"379751\" data-index=\"1\"><a class=\"content-row w-100 bgc-glass\" tabindex=\"-1\" href=\"https:\/\/www.genesys.com\/de-de\/customer-stories\/dental-axess\"><div class=\"customer-image-col\"><img decoding=\"async\" class=\"header-image\" alt=\"Dentist explaining procedure to patient sitting in dentists chair\" src=\"https:\/\/www.genesys.com\/media\/Dental-Axess-hero.jpg\" width=\"626\" height=\"353\"><\/div><div class=\"customer-quote-col\"><p class=\"quote-content mb-2 quote-size-md\">\u201eMit WhatsApp senden uns Kunden jetzt einfach Screenshots und Bilder zu, sodass unsere Experten das Problem schnell erkennen und Abhilfema\u00dfnahmen vorschlagen k\u00f6nnen. Auch die Handhabung von Anfragen \u00fcber verschiedene Kan\u00e4le ist kein Problem: Die Genesys Cloud CX-Anwendung macht's m\u00f6glich.\u201c<\/p><p class=\"customer-name text-18 font-weight-bold mb-0\">Patricia Zoller<\/p><p class=\"customer-title\">Marketing Manager<\/p><div class=\"btn-container\"><div class=\"btn btn-secondary small\">Kundenbericht lesen<\/div><\/div><\/div><\/a><\/div><button aria-label=\"Next panel\" title=\"Next panel\" class=\"next-control carousel-controls\"><\/button><\/div><\/div><\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section flair=&#8220;%5B%7B%22flair_type%22%3A%22f_type_image%22%2C%22hide_mobile%22%3A%22yes%22%7D%5D&#8220;][vc_row equal_height=&#8220;yes&#8220;][vc_column width=&#8220;1\/2&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h2>Erfahren Sie, wie Genesys Sie noch unterst\u00fctzen kann<\/h2>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/2&#8243; elemental_order=&#8220;order-5&#8243; offset=&#8220;vc_col-md-6&#8243;]<div class=\"btn-container justify-content-lg-end justify-content-center\"><a role=\"button\"  class=\"btn chevron btn-secondary\" href=\"\/de-de\/capabilities\" target=\"\" rel=\"\">Alle Funktionen anzeigen<\/a><\/div>[\/vc_column][vc_column]<div class=\"capability-list icon-card-bg row gutter-small\"><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/co-browse-screenshare\"><div class=\"card-body\"><h3 class=\"h5\">Co-Browsing und Bildschirmfreigabe<\/h3><p>Sehen Sie in Echtzeit, warum sich Ihre Kunden an Sie wenden. Zeigen Sie ihnen, wie sie ihre Probleme l\u00f6sen k\u00f6nnen.<\/p><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/digital\"><div class=\"card-body\"><h3 class=\"h5\">Digitales Kundenengagement<\/h3><p>Unterst\u00fctzen Sie Ihre Teams mit einer umfassenden Suite von digitalen Funktionen\u00a0\u2013 oder mit Ihrer eigenen L\u00f6sung.<\/p><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/email-contact-center\"><div class=\"card-body\"><h3 class=\"h5\">E-Mail<\/h3><p>Erweitern Sie Ihr ServiceNow CSM-System um eine f\u00fchrende cloudbasierte Contact Center-L\u00f6sung mit leistungsstarker vorkonfigurierter Integration und heben Sie Ihre CX auf die n\u00e4chste Ebene.<\/p><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/live-chat-software\"><div class=\"card-body\"><h3 class=\"h5\">Live-Chat<\/h3><p>Chatten Sie mit Interessenten und Kunden in Echtzeit, um Probleme schnell zu l\u00f6sen\u00a0\u2013 kein Telefonanruf erforderlich.<\/p><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/sms-messaging\"><div class=\"card-body\"><h3 class=\"h5\">SMS und Messaging<\/h3><p>Nutzen Sie bekannte mobile Kan\u00e4le, um mit Ihren Kunden in Kontakt zu treten, ohne ihren Tagesablauf zu unterbrechen.<\/p><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/social-media-customer-service\"><div class=\"card-body\"><h3 class=\"h5\">Social Media und Messaging-Apps<\/h3><p>Sprechen Sie Ihre Kunden auf beliebten Plattformen an, die sie bereits verwenden, darunter WhatsApp, Facebook und Instagram, und nutzen Sie Social Listening-Funktionen, um \u00f6ffentliche Gespr\u00e4che miteinzubeziehen.<\/p><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/knowledge-management\"><div class=\"card-body\"><h3 class=\"h5\">Tools f\u00fcr das Wissensmanagement<\/h3><p>Stellen Sie mit KI-gest\u00fctzten Tools f\u00fcr das Wissensmanagement jederzeit die richtigen Informationen bereit. \r\n<\/p><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/virtual-agents\"><div class=\"card-body\"><h3 class=\"h5\">Virtueller Agent<\/h3><p>Verbessern Sie den Self-Service mit KI-gest\u00fctzten Chatbots, die den Kontext der Interaktion verstehen und wie menschliche Mitarbeiter agieren, um jederzeit eine herausragende Erfahrung zu bieten.<\/p><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/predictive-web-engagement\"><div class=\"card-body\"><h3 class=\"h5\">Vorausschauende Interaktion<\/h3><p>Nutzen Sie KI, um Online-Kunden im richtigen Moment proaktiv mit dem n\u00e4chstbesten Angebot oder der n\u00e4chstbesten Ressource zu binden.<\/p><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/work-automation-and-task-routing\"><div class=\"card-body\"><h3 class=\"h5\">Work Automation und Task Routing<\/h3><p>Nutzen Sie pr\u00e4zise, einheitliche Daten, um fundiertere Entscheidungen in Ihrem gesamten Back Office zu treffen.<\/p><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section flair=&#8220;%5B%7B%22flair_type%22%3A%22f_type_image%22%2C%22hide_mobile%22%3A%22yes%22%7D%5D&#8220;][vc_row][vc_column width=&#8220;1\/2&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h2>Bessere Customer Experience mit WhatsApp und mehr auf Genesys Cloud<\/h2>\n<p>[\/vc_column_text][\/vc_column][vc_column elemental_order=&#8220;order-5&#8243; offset=&#8220;vc_col-md-6&#8243;]<div class=\"btn-container justify-content-lg-end justify-content-center\"><a role=\"button\"  class=\"btn chevron btn-secondary\" href=\"\/de-de\/resources\" target=\"\" rel=\"\">Alle Ressourcen ansehen<\/a><\/div>[\/vc_column][vc_column]<div class=\"related-posts-container next-steps-module w-100\"><div class=\"inner-container scrollable-row-container\"><div class=\"row align-items-stretch gutter-small col-count-3 scrollable-row\"><div class=\"col-md-4 vertical-cards grid-item card-col item-image grid_type-resources\"><a class=\"card w-100 h-100 bgc-lgray component vertical text-start thumbnail chevron-only\" href=\"https:\/\/www.genesys.com\/de-de\/resources\/work-automation-and-task-routing\"><div class=\"thumbnail-col thubmnail\"><img decoding=\"async\" src=\"https:\/\/www.genesys.com\/media\/Work-automation-task-routing_DE.png\" height=\"697\" width=\"1351\" alt=\"Work automation &#038; task routing de\"><\/div><div class=\"card-body text-col\"><p class=\"assettag\">Product overview<\/p><h3 class=\"item-title h6\">Arbeitsautomatisierung und Aufgaben-Routing<\/h3><\/div><div class=\"card-footer text-end\"><div class=\"justify-content-end btn-container\"><div class=\"btn chevron small only btn-secondary\"><\/div><\/div><\/div><\/a><\/div><div class=\"col-md-4 vertical-cards grid-item card-col item-image grid_type-resources\"><a class=\"card w-100 h-100 bgc-lgray component vertical text-start thumbnail chevron-only\" href=\"https:\/\/www.genesys.com\/de-de\/resources\/state-of-cx\"><div class=\"thumbnail-col thubmnail\"><img decoding=\"async\" src=\"https:\/\/www.genesys.com\/media\/DE-SoCX-26-Cover.png\" height=\"800\" width=\"1330\" alt=\"Stand der customer experience 2026\"><\/div><div class=\"card-body text-col\"><p class=\"assettag\">Bericht<\/p><h3 class=\"item-title h6\">Der aktuelle Stand der Customer Experience<\/h3><\/div><div class=\"card-footer text-end\"><div class=\"justify-content-end btn-container\"><div class=\"btn chevron small only btn-secondary\"><\/div><\/div><\/div><\/a><\/div><div class=\"col-md-4 vertical-cards item-image grid-item card-col item-image grid_type-\"><a class=\"card w-100 h-100 bgc-lgray component vertical text-start thumbnail chevron-only\" href=\"https:\/\/appfoundry.genesys.com\/filter\/genesyscloud\/listing\/ff1b6df3-e0ac-44ac-909b-4cc1959823ca\"><div class=\"thumbnail-col thubmnail\"><img decoding=\"async\" src=\"https:\/\/www.genesys.com\/media\/resource-thumb-appfoundry-2024.png\" height=\"785\" width=\"1440\" alt=\"Resource thumb appfoundry 2024\"><\/div><div class=\"card-body text-col\"><h3 class=\"item-title h6\">Testen und kaufen: Work Automation<\/h3><\/div><div class=\"card-footer text-end\"><div class=\"justify-content-end btn-container\"><div class=\"btn chevron small only btn-secondary\"><\/div><\/div><\/div><\/a><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section sec_modern_width=&#8220;enable&#8220; background_color=&#8220;bgc-lgray&#8220; flair=&#8220;%5B%7B%22flair_type%22%3A%22f_type_image%22%2C%22hide_mobile%22%3A%22yes%22%7D%5D&#8220; css=&#8220;.vc_custom_1741334671940{background-image: url(https:\/\/www.genesys.com\/media\/Threads-Right-Wave.png?id=549945) !important;}&#8220; el_class=&#8220;px-0 py-2 px-md-5 py-md-5&#8243; el_id=&#8220;demo&#8220;][vc_row background_color=&#8220;bgc-glass&#8220; content_placement=&#8220;middle&#8220; el_class=&#8220;form-card&#8220;][vc_column width=&#8220;5\/12&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h2>Transformieren Sie Ihre Customer Experience mit WhatsApp<\/h2>\n<p>Erfahren Sie, wie Sie mit Genesys Cloud in gro\u00dfem Ma\u00dfstab vernetzte, KI-gest\u00fctzte Kundeninteraktionen auf WhatsApp bieten k\u00f6nnen. Machen Sie noch heute den ersten Schritt zu h\u00f6herer Effizienz, k\u00fcrzeren Reaktionszeiten, mehr Personalisierung und zufriedeneren Kunden.[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/2&#8243; offset=&#8220;vc_col-sm-offset-1&#8243;]<div class=\"eloq_form elq-container gmkto_form_type_hot gmkto_format_vertical\"><form method=\"post\" name=\"MasterLeadIntakeForm\" action=\"https:\/\/s1260946616.t.eloqua.com\/e\/f2\" data-proc=\"inline\" data-ppcount=\"5\" onsubmit=\"return proc_submit(this);\" class=\"beam-form elq-form init no-bg-form yesknown yesprefill yespp strict-check\"  data-target=\".thank-you\" ><div id=\"known_person\" style=\"display:none;\"><p class=\"welcome_user\"><span id=\"welcome_person\">Willkommen zur\u00fcck<\/span> <span id=\"person_info\"><span class=\"person_first\"><\/span>&nbsp;<span class=\"person_last\"><\/span><\/span><\/p><p class=\"delete_button\"><a class=\"deletemyrecord\">Nicht du?<\/a><\/p><\/div><input value=\"MasterLeadIntakeForm\" type=\"hidden\" name=\"elqFormName\"><input value=\"1260946616\" type=\"hidden\" name=\"elqSiteId\"><input name=\"elqCampaignId\" type=\"hidden\"><input type=\"hidden\" name=\"elqCustomerGUID\" value=\"\"><input type=\"hidden\" name=\"elqCookieWrite\" value=\"0\"><input type=\"hidden\" name=\"client_ip_address\" id=\"fe449\" value=\"\"><div class=\"fields\"><input type=\"hidden\" name=\"CID\" id=\"fe198\" value=\"7010d000001KeaxAAC\"><input type=\"hidden\" name=\"CID_STATUS\" id=\"fe281\" value=\"\"><input type=\"hidden\" name=\"redirect_url\" id=\"fe217\" value=\"\"><input type=\"hidden\" name=\"landing_page_url\" id=\"fe204\" value=\"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/capabilities\/626008\"><input type=\"hidden\" name=\"post_type\" id=\"fe448\" value=\"capabilities\"><input type=\"hidden\" name=\"integration\" id=\"fe362\" value=\"\"><input type=\"hidden\" name=\"language_code\" id=\"fe479\" value=\"de-de\"><input type=\"hidden\" name=\"full_url\" id=\"fe983\" value=\"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/capabilities\/626008\"><input type=\"hidden\" name=\"post_id\" id=\"fe984\" value=\"485663\">\n    <div class=\"form-row row-email el_field form-floating\">\n        <input type=\"email\" class=\"form-control el_field elq-item-input required\" name=\"emailAddress\" id=\"fe192\" value=\"\" aria-label=\"Gesch\u00e4ftliche E-Mail\" placeholder=\"Gesch\u00e4ftliche E-Mail\">\n        <label for=\"fe192\">Gesch\u00e4ftliche E-Mail<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available el_field form-floating\">\n        <input type=\"text\" class=\"form-control el_field elq-item-input cb_available  required\" name=\"firstName\" id=\"fe190\" value=\"\" placeholder=\"Vorname\">\n        <label for=\"fe190\">Vorname<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available el_field form-floating\">\n        <input type=\"text\" class=\"form-control el_field elq-item-input cb_available required\" name=\"lastName\" id=\"fe191\" value=\"\" placeholder=\"Nachname\">\n        <label for=\"fe191\">Nachname<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row form-floating el_field\">\n        <input type=\"tel\" class=\"form-control el_field elq-item-input required pre-exclude\" name=\"busPhone\" id=\"fe215\" value=\"\" placeholder=\"Telefon\">\n        <label for=\"fe215\">Telefon<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe219\" name=\"jobLevel1\" data-value=\"\">\n            <option selected=\"\" value=\"\"><\/option><option value=\"C-Level\">Vorstand<\/option><option value=\"VP\">VP<\/option><option value=\"Director\">Director<\/option><option value=\"Manager\">Manager<\/option><option value=\"Principal\">Federf\u00fchrender Partner<\/option><option value=\"Engineer \/ Architect\">Ingenieur\/Architekt<\/option><option value=\"Consultant\">Berater<\/option><option value=\"Analyst\">Analyst<\/option><option value=\"Partner\">Partner<\/option><option value=\"Staff\">Mitarbeiter<\/option><option value=\"Unknown\">Unbekannt<\/option>\n        <\/select>\n        <label for=\"fe219\">Position<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe218\" name=\"jobFunction1\" data-value=\"\">\n            <option selected=\"\" value=\"\"><\/option>\n            <option value=\"Claims\">Forderungen<\/option><option value=\"Collections\">Forderungsmanagement<\/option><option value=\"Contact Center Management\">Contact Center-Management<\/option><option value=\"Customer Experience\">Customer\u00a0Experience<\/option><option value=\"Customer Service\">Kundenservice<\/option><option value=\"Ecommerce\/Digital Channels\">E-Commerce\/digitale Kan\u00e4le<\/option><option value=\"Finance\">Finanzen<\/option><option value=\"Human Resources\">Personalwesen<\/option><option value=\"Influencer\">Influencer<\/option><option value=\"Information Technology\">IT<\/option><option value=\"IT Architecture\">IT-Architektur<\/option><option value=\"IT Infrastructure\">IT-Infrastruktur<\/option><option value=\"IVR\">IVR<\/option><option value=\"Marketing\">Marketing<\/option><option value=\"Operations \/ Process Management\">Betriebs-\/Prozessmanagement<\/option><option value=\"Production Management\">Produktionsleitung<\/option><option value=\"Purchasing\">Kauf<\/option><option value=\"Sales\">Vertrieb<\/option><option value=\"Unknown\">Unbekannt<\/option>\n        <\/select>\n        <label for=\"fe218\">Anwendungsbereiche<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <input type=\"text\" class=\"form-control el_field elq-item-input cb_available required eloq_ppe\" name=\"company\" id=\"fe193\" value=\"\" placeholder=\"Unternehmensname\">\n        <label for=\"fe193\">Unternehmensname<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe194\" name=\"country\" data-value=\"\">\n            <option value=\"\"><\/option>\n            <!-- Add country options here -->\n        <\/select>\n        <label for=\"fe194\">Land<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available country_dep el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe214\" name=\"stateProv\" data-value=\"\">\n            <option selected=\"\" value=\"\"><\/option>\n        <\/select>\n        <label for=\"fe214\">State\/Province<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <input type=\"text\" class=\"form-control el_field elq-item-input cb_available required eloq_ppe\" name=\"website1\" id=\"fe801\" value=\"\" placeholder=\"Ihre Website\">\n        <label for=\"fe801\">Ihre Website<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <input type=\"text\" class=\"form-control el_field elq-item-input cb_available required eloq_ppe\" name=\"city\" id=\"fe226\" value=\"\" placeholder=\"Stadt\">\n        <label for=\"fe226\">Stadt<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <input type=\"text\" class=\"form-control el_field elq-item-input cb_available required eloq_ppe\" name=\"title\" id=\"fe220\" value=\"\" placeholder=\"Jobtitel\">\n        <label for=\"fe220\">Jobtitel<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe221\" name=\"industry1\" data-value=\"\">\n            <option value=\"\" ><\/option>\n            <option value=\"Banking\">Bankwesen<\/option><option value=\"Business Services\">Unternehmensdienstleistungen<\/option><option value=\"Capital Markets\">Capital Markets<\/option><option value=\"Communications\">Communications<\/option><option value=\"Consumer Products\">Consumer Products<\/option><option value=\"Defense & Intelligence\">Defense & Intelligence<\/option><option value=\"Education & Non-Profit\">Education & Non-Profit<\/option><option value=\"Energy & Utilities\">Energie- und Versorgungsunternehmen<\/option><option value=\"Entertainment\">Unterhaltungsbranche<\/option><option value=\"Government\">Beh\u00f6rden<\/option><option value=\"Insurance\">Versicherungen<\/option><option value=\"Life Sciences\">Life Sciences<\/option><option value=\"Logistics\">Logistics<\/option><option value=\"Manufacturing\">Manufacturing<\/option><option value=\"Payors\">Payors<\/option><option value=\"Providers\">Providers<\/option><option value=\"Retailers\">Retailers<\/option><option value=\"Technology\">Technologie<\/option><option value=\"Travel & Hospitality\">Travel & Hospitality<\/option><option value=\"Retail Banking\">Retail Banking<\/option><option value=\"Other\">Sonstige<\/option>\n        <\/select>\n        <label for=\"fe221\">Branche<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe222\" name=\"levelofInterest1\" data-value=\"\">\n            <option value=\"\"><\/option>\n            <option value=\"Just researching\">\u2026 informiere mich nur<\/option><option value=\"Gathering business requirements\">\u2026 recherchiere die Anforderungen<\/option><option value=\"Comparing solutions\">\u2026 vergleiche L\u00f6sungen<\/option><option value=\"Ready for a conversation\">\u2026 bin an einem Gespr\u00e4ch interessiert<\/option>\n        <\/select>\n        <label for=\"fe222\">Ich \u2026<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe225\" name=\"numberofAgentsForm1\" data-value=\"\">\n            <option value=\"\"><\/option>\n            <option value=\"1-20\">1-20<\/option><option value=\"21-50\">21\u201350<\/option><option value=\"51-100\">51\u2013100<\/option><option value=\"101-300\">101\u2013300<\/option><option value=\"301-500\">301\u2013500<\/option><option value=\"501-1000\">501\u20131000<\/option><option value=\">1000\">&gt;1000<\/option><option value=\"No Contact Center\">Kein Contact\u00a0Center<\/option><option value=\"Don't Know\">Ich wei\u00df es nicht<\/option>\n        <\/select>\n        <label for=\"fe225\">Anzahl der Arbeitspl\u00e4tze im Contact Center<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div><div class=\"form-check single-checkbox-row form-row gdpr-field white-box required\"><input type=\"checkbox\" class=\"el_field eloq_ppe\" name=\"explicitConsentEmailPhone\" id=\"fe224\" val=\"\"><label class=\"checkbox-aligned elq-item-label\" for=\"fe224\">Ja. Ich m\u00f6chte per E-Mail oder Telefon \u00fcber Neuigkeiten zu Genesys auf dem Laufenden gehalten werden.<\/label><\/div><div class=\"single-checkbox-row form-row white-box \"><input type=\"checkbox\" class=\"el_field eloq_ppe\" name=\"contactMe\" id=\"fe509\" val=\"\"><label class=\"checkbox-aligned elq-item-label\" for=\"fe509\">Ich h\u00e4tte es gern, dass mich jemand kontaktiert.<\/label><\/div><input type=\"hidden\" data-query=\"utm_medium\" name=\"utm_medium\" id=\"fe199\" value=\"\"><input type=\"hidden\" data-query=\"utm_source\" name=\"utm_source\" id=\"fe200\" value=\"\"><input type=\"hidden\" data-query=\"utm_campaign\" name=\"utm_campaign\" id=\"fe201\" value=\"\"><input type=\"hidden\" data-query=\"utm_term\" name=\"utm_term\" id=\"fe202\" value=\"\"><input type=\"hidden\" data-query=\"utm_content\" name=\"utm_content\" id=\"fe203\" value=\"\"><input type=\"hidden\" data-query=\"ost_tool\" name=\"ost_tool\" id=\"fe293\" value=\"\"><input type=\"hidden\" data-query=\"ost_campaign\" name=\"ost_campaign\" id=\"fe294\" value=\"\"><input type=\"hidden\" data-query=\"ost_content\" name=\"ost_content\" id=\"fe295\" value=\"\"><input type=\"hidden\" data-query=\"blaid\" name=\"eloquaBLAID_c\" id=\"fe3099\" value=\"\"><input type=\"hidden\" data-query=\"gclid\" name=\"gCLID1\" id=\"fe283\" value=\"\"><input type=\"hidden\" data-query=\"mkwid\" name=\"mKWID1\" id=\"fe678\" value=\"\"><input type=\"hidden\" name=\"gAClientID1\" id=\"fe284\" value=\"\"><input type=\"hidden\" name=\"noteCreatorTitle1\" id=\"fe313\" value=\"\"><input type=\"hidden\" name=\"webContentAutoResponderDefault\" id=\"fe286\" value=\"Hot Lead\"><input type=\"hidden\" name=\"webContentAutoResponderTitle\" id=\"fe287\" value=\"\"><input type=\"hidden\" name=\"webContentAutoResponderURL\" id=\"fe288\" value=\"\"><input type=\"hidden\" name=\"noteCreator2\" id=\"fe478\" value=\"\"><input type=\"hidden\" class=\"yesprefill\" name=\"neverbounceResult1\" id=\"fe640\" value=\"OFF\"><input type=\"hidden\" class=\"yesprefill\" name=\"neverbounceFlags1\" id=\"fe641\" value=\"OFF\"><input type=\"hidden\" class=\"yesprefill\" name=\"neverbounceSuggestedCorrection1\" id=\"fe642\" value=\"6sense\"><input type=\"hidden\" name=\"clearbitPersonID1\" id=\"fe630\" value=\"\"><input type=\"hidden\" name=\"clearbitFieldCount1\" id=\"fe633\" value=\"\"><input type=\"hidden\" name=\"clearbitTitle1\" id=\"fe646\" value=\"\"><input type=\"hidden\" name=\"clearbitRole1\" id=\"fe631\" value=\"\"><input type=\"hidden\" name=\"clearbitNumberofEmployees1\" id=\"fe647\" value=\"\"><input type=\"hidden\" name=\"clearbitNumberofEmployeesRange1\" id=\"fe648\" value=\"\"><input type=\"hidden\" name=\"clearbitWebsite1\" id=\"fe802\" value=\"\"><input type=\"hidden\" name=\"browserUserAgent\" id=\"fe3319\" value=\"\"><input type=\"text\" class=\"honeypp\" name=\"honeypp\" id=\"honeypp\" value=\"\" ><input role=\"button\" aria-label=\"Demo anfordern\" type=\"Submit\" class=\"submit-button-style btn btn-primary \" value=\"Demo anfordern\" id=\"fe195\"><div class=\"loading\"><\/div><div class=\"gdpr-field form-row white-box legal\"><span>Durch die Bereitstellung Ihrer Informationen erkl\u00e4ren Sie sich mit unseren <a href=\"https:\/\/www.genesys.com\/de-de\/company\/legal-docs\/datenschutzerklaerung\" target=\"_blank\">Datenschutzbestimmungen<\/a> einverstanden<\/span><\/div><\/div><\/form><\/div>[vc_column_text css=&#8220;&#8220; el_class=&#8220;thank-you&#8220;]<\/p>\n<p class=\"h4\">Vielen Dank f\u00fcr Ihr Interesse.<\/p>\n<p>Wir melden uns bei Ihnen, um einen f\u00fcr Sie passenden Termin zu vereinbaren.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section flair=&#8220;%5B%7B%22hide_mobile%22%3A%22yes%22%7D%5D&#8220;][vc_row][vc_column width=&#8220;5\/12&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h2>H\u00e4ufig gestellte Fragen zu WhatsApp CX<\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;5\/6&#8243; offset=&#8220;vc_col-sm-offset-1&#8243;]<div class=\"component-accordion-container no-title\" data-display=\"accordion\"><div class=\"component-accordion-content custom-accordion\" data-opened=\"1\"><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Wie unterscheidet sich dies von anderen Kundenservice-Plattforml\u00f6sungen mit WhatsApp?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Im Gegensatz zu separaten Integrationen ist WhatsApp nativ in Genesys Cloud eingebettet. Dies erm\u00f6glicht eine vollst\u00e4ndige Orchestrierung der Journey bei persistentem Kontext und nahtlosen \u00dcberg\u00e4ngen zwischen verschiedenen Kan\u00e4len. <\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Wie lange dauert die Bereitstellung von WhatsApp in Genesys Cloud?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Mit dem in Genesys Cloud eingebetteten WhatsApp-Anmeldeprozess k\u00f6nnen Unternehmen die WhatsApp Business Platform direkt in Genesys Cloud \u00fcbernehmen. Die gef\u00fchrte Einrichtung vereinfacht die Kontoerstellung, die Registrierung von Telefonnummern und die Konfiguration von Meta Business Manager.<\/p>\n<p>Nach erfolgter Einrichtung k\u00f6nnen Benutzer Telefonnummern, Gesch\u00e4ftsprofile und Nachrichtenvorlagen in Meta Business Manager verwalten und gleichzeitig auf Messaging-Einblicke in Genesys Cloud zugreifen.<\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Wie verbessert KI die WhatsApp-Erfahrung?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Agentische virtuelle Agenten verstehen Absichten, ergreifen Ma\u00dfnahmen und l\u00f6sen Probleme v\u00f6llig autonom, w\u00e4hrend der Agent Copilot menschliche Mitarbeiter in Echtzeit unterst\u00fctzt.<\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Wie stimmen Kunden dem Erhalt von Nachrichten \u00fcber WhatsApp zu?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Meta verlangt die ausdr\u00fcckliche Zustimmung f\u00fcr die Nutzung von WhatsApp-Nachrichten. Die Zustimmung und damit die Einhaltung der Meta-Richtlinien kann \u00fcber das IVR-System, eine Webseite oder per SMS erfasst werden. Weitere Einzelheiten finden Sie auf der <a href=\"https:\/\/developers.facebook.com\/docs\/whatsapp\/overview\/getting-opt-in\" target=\"_blank\" rel=\"noopener\">Meta-Entwicklerseite<\/a>.<\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Wie funktioniert Sprache innerhalb von WhatsApp?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Kunden k\u00f6nnen Sprachnachrichten senden oder \u00fcber Business Calling Live-Sprachanrufe initiieren, wobei der Kontext innerhalb desselben Gespr\u00e4chs erhalten bleibt. <\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Welche Arten von Interaktionen werden unterst\u00fctzt?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Von proaktiven Benachrichtigungen und Kampagnen bis hin zu Serviceanfragen und Probleml\u00f6sungen k\u00f6nnen Unternehmen mithilfe umfangreicher Messaging-Funktionen eine breite Palette von Interaktionen anbieten. <\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Wird WhatsApp auch mit einem hohen Aufkommen von Kundeninteraktionen fertig?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Ja. Mit Genesys Cloud k\u00f6nnen Contact\u00a0Center-Interaktionen \u00fcber WhatsApp skaliert werden, um hohe Aufkommen zu bew\u00e4ltigen. Dies gilt sowohl technisch, da die L\u00f6sung auf hohen Durchsatz ausgelegt ist, als auch logistisch f\u00fcr Marken durch Automatisierung, KI und kampagnenbasierte Kontaktaufnahme. Unternehmen k\u00f6nnen virtuelle Agenten, automatisierte Arbeitsabl\u00e4ufe und proaktives Messaging nutzen, um effizient eine gro\u00dfe Anzahl von Gespr\u00e4chen zu verwalten und dabei die Qualit\u00e4t und Reaktionsf\u00e4higkeit zu wahren.<\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Wann sollten Gespr\u00e4che von der KI und wann von einer Person gehandhabt werden?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>KI eignet sich am besten f\u00fcr routinem\u00e4\u00dfige Interaktionen mit hohem Aufkommen, etwa h\u00e4ufig gestellte Fragen, Abfragen des Bestellstatus, Terminplanungen und anf\u00e4ngliche Priorit\u00e4tszuweisungen. Agentische virtuelle Agenten von Genesys k\u00f6nnen v\u00f6llig autonom Absichten verstehen, Ma\u00dfnahmen ergreifen und eine Vielzahl von Anfragen l\u00f6sen. Bei komplexeren, vertraulichen oder besonders wichtigen Interaktionen k\u00f6nnen Gespr\u00e4che nahtlos an einen Mitarbeiter weitergeleitet werden, wobei der vollst\u00e4ndige Kontext gewahrt bleibt, um ein reibungsloses Kundenerlebnis zu gew\u00e4hrleisten.<\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Bietet WhatsApp die n\u00f6tige Sicherheit f\u00fcr die Kundenkommunikation?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Ja. WhatsApp verwendet End-to-End-Verschl\u00fcsselung zum Schutz von Nachrichten und erm\u00f6glicht so eine sichere Kommunikation zwischen Unternehmen und Kunden. Beim Einsatz mit Genesys Cloud profitieren Unternehmen zudem von Sicherheit, Compliance und Governance-Funktionen auf Unternehmensniveau, die zum Datenschutz und zur Einhaltung gesetzlicher Vorschriften beitragen.<\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Was sind h\u00e4ufige Anwendungsf\u00e4lle f\u00fcr WhatsApp im Bereich der Customer Experience?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Zu h\u00e4ufigen Anwendungsf\u00e4llen geh\u00f6ren proaktive Benachrichtigungen (Lieferupdates, Zahlungserinnerungen usw.), Support und Probleml\u00f6sung f\u00fcr Kunden, Terminplanung, Sendungsverfolgung, Serviceanfragen, Betrugswarnungen und vieles mehr. Unternehmen k\u00f6nnen auch inhaltsreiche, interaktive Gespr\u00e4che mit Medien, Schaltfl\u00e4chen und Listen nutzen und bei Bedarf \u00fcber Business Calling zu Sprachanrufen \u00fcbergehen.<\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">K\u00f6nnen Unternehmen WhatsApp weltweit f\u00fcr Kundeninteraktionen nutzen?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Ja. WhatsApp ist eine der weltweit am h\u00e4ufigsten genutzten Messaging-Plattformen und damit ideal f\u00fcr Interaktionen mit internationalen Kunden geeignet. Mit Genesys Cloud k\u00f6nnen Unternehmen mehrsprachige Interaktionen bieten, globale Abl\u00e4ufe von einer einheitlichen Plattform aus verwalten und konsistente, personalisierte Erlebnisse \u00fcber Regionen hinweg bereitstellen.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div>[\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_section background_color=&#8220;bgc-lgray&#8220; flair=&#8220;%5B%7B%7D%5D&#8220; vib=&#8220;enable&#8220; css=&#8220;.vc_custom_1714410887619{background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8220;][vc_row content_placement=&#8220;middle&#8220; vib=&#8220;enable&#8220; vib_top=&#8220;6.333rem&#8220;][vc_column][\/vc_column][vc_column width=&#8220;5\/12&#8243;][vc_column_text css=&#8220;&#8220;] WhatsApp-Integration in Genesys Cloud f\u00fcr Unternehmen KI-gest\u00fctzter Messaging- und Anruf-Service f\u00fcr Unternehmen, direkt in WhatsApp [\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/2&#8243; offset=&#8220;vc_col-lg-offset-1 vc_col-md-offset-1 vc_col-sm-offset-0&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_section background_color=&#8220;bgc-lgray&#8220; flair=&#8220;%5B%7B%22flair_type%22%3A%22f_type_image%22%2C%22hide_mobile%22%3A%22yes%22%7D%5D&#8220;][vc_row][vc_column width=&#8220;7\/12&#8243; offset=&#8220;vc_col-md-offset-0 vc_col-sm-offset-0&#8243;][vc_column_text css=&#8220;&#8220;] Bieten Sie eine skalierbare, vernetzte WhatsApp-Erfahrung mit KI-gest\u00fctzter Orchestrierung und Automatisierung Genesys Cloud [&hellip;]<\/p>\n","protected":false},"author":1225,"featured_media":0,"template":"","tax_cap_lobby":[18115,18118],"tax_priority":[],"tax_contenttheme":[],"tax_bundle":[],"tax_contenttheme2":[],"tax_capability_sitewide":[],"tax_products_programs":[],"tax_buying_job":[],"tax_buyer_persona":[],"tax_sector":[],"tax_segment":[],"class_list":["post-626008","capabilities","type-capabilities","status-publish","hentry","tax_cap_lobby-ai-and-automation-de-de","tax_cap_lobby-digital-de-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/capabilities\/626008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/capabilities"}],"about":[{"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/types\/capabilities"}],"author":[{"embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/users\/1225"}],"version-history":[{"count":10,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/capabilities\/626008\/revisions"}],"predecessor-version":[{"id":635764,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/capabilities\/626008\/revisions\/635764"}],"wp:attachment":[{"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/media?parent=626008"}],"wp:term":[{"taxonomy":"tax_cap_lobby","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_cap_lobby?post=626008"},{"taxonomy":"tax_priority","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_priority?post=626008"},{"taxonomy":"tax_contenttheme","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_contenttheme?post=626008"},{"taxonomy":"tax_bundle","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_bundle?post=626008"},{"taxonomy":"tax_contenttheme2","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_contenttheme2?post=626008"},{"taxonomy":"tax_capability_sitewide","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_capability_sitewide?post=626008"},{"taxonomy":"tax_products_programs","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_products_programs?post=626008"},{"taxonomy":"tax_buying_job","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_buying_job?post=626008"},{"taxonomy":"tax_buyer_persona","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_buyer_persona?post=626008"},{"taxonomy":"tax_sector","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_sector?post=626008"},{"taxonomy":"tax_segment","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_segment?post=626008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}