{"id":449924,"date":"2021-09-01T12:10:19","date_gmt":"2021-09-01T19:10:19","guid":{"rendered":"https:\/\/www.genesys.com\/capabilities\/wissensmanagement-tools"},"modified":"2026-02-10T21:55:26","modified_gmt":"2026-02-11T05:55:26","slug":"knowledge-management","status":"publish","type":"capabilities","link":"https:\/\/www.genesys.com\/de-de\/capabilities\/knowledge-management","title":{"rendered":"Tools f\u00fcr das Wissensmanagement"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section background_color=&#8220;bgc-lgray&#8220; flair=&#8220;%5B%7B%22flair_type%22%3A%22f_type_image%22%2C%22hide_mobile%22%3A%22yes%22%7D%5D&#8220; css=&#8220;.vc_custom_1762451883407{background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8220;][vc_row content_placement=&#8220;middle&#8220; el_class=&#8220;no-shadow&#8220;][vc_column]<div class=\"component breadcrumbs theme-\"><div class=\"links-row w-100 d-flex flex-wrap align-items-center justify-content-start\"><div class=\"link-col\"><a class=\"breadcrumb-link\" href=\"\/de-de\/capabilities\">Funktionen<\/a><\/div><div class=\"link-col\"><a class=\"breadcrumb-link\" href=\"\/de-de\/capabilities\/ai-and-automation\">K\u00fcnstliche Intelligenz und Automatisierung<\/a><\/div><\/div><\/div>[\/vc_column][vc_column width=&#8220;5\/12&#8243; el_class=&#8220;order-md-1 order-5&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h1>Genesys Cloud Knowledge Fabric<\/h1>\n<p class=\"text-22\">Vereinheitlichen Sie Unternehmenswissen in einer adaptiven Fabric, die agentische KI unterst\u00fctzt und die besten Antworten auf jede Frage liefert.<\/p>\n<p>[\/vc_column_text]<div class=\"btn-container  \"><a role=\"button\"  class=\"btn btn-primary\" href=\"#demo\" target=\"\" rel=\"\">Demo buchen<\/a><\/div>[\/vc_column][vc_column width=&#8220;1\/2&#8243; offset=&#8220;vc_col-sm-offset-1&#8243;][vc_single_image image=&#8220;611981&#8243; css=&#8220;&#8220; rounded_corners=&#8220;rounded-lg&#8220;][\/vc_column][\/vc_row][\/vc_section][vc_section][vc_row][vc_column width=&#8220;5\/12&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h2>Smartes, vernetztes Wissensmanagement<\/h2>\n<p>Bauen Sie ein umfassendes Informations\u00f6kosystem auf, sodass Agenten, Vorgesetzte und Kunden das n\u00f6tige Wissen stets gleich zur Hand haben. Beantworten Sie Fragen in dem passenden Kontext, bauen Sie Ihr \u00d6kosystem aus und passen Sie es kontinuierlich an, um das Wissen im Laufe der Zeit zu verbessern.[\/vc_column_text][\/vc_column][\/vc_row][vc_row equal_height=&#8220;yes&#8220;][vc_column width=&#8220;1\/3&#8243;][vc_column_text ct_style=&#8220;list-block&#8220; css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Unternehmenswissen vorbereiten und vereinheitlichen<\/h3>\n<p>Bringen Sie alle Wissensquellen, einschlie\u00dflich CRM-Systeme, Intranets, Wikis und Legacy-Repositories, in einer einheitlichen Struktur zusammen.[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/3&#8243;][vc_column_text ct_style=&#8220;list-block&#8220; css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Kontextbezogene, personalisierte Antworten liefern<\/h3>\n<p>Knowledge Fabric nutzt Absicht und Kontext, um die richtigen Informationen f\u00fcr konsistente, intelligente Erlebnisse \u00fcber alle Kan\u00e4le hinweg bereitzustellen.[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/3&#8243;][vc_column_text ct_style=&#8220;list-block&#8220; css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Lernen, anpassen und kontinuierlich verbessern<\/h3>\n<p>\u00dcberblicken Sie in Echtzeit, wie Wissen genutzt wird und wo L\u00fccken bestehen. Integrierte Analysen helfen Ihnen, bei jeder Interaktion das \u00d6kosystem zu optimieren.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section flair=&#8220;%5B%7B%22flair_type%22%3A%22f_type_image%22%7D%5D&#8220;][vc_row][vc_column width=&#8220;5\/12&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h2>Auf Intelligenz, Orchestrierung und Vertrauen ausgerichtet<\/h2>\n<p>Geben Sie Agenten und Kunden mithilfe von KI einfachen Zugang zu dem Wissen, das sie brauchen, wenn sie es brauchen.[\/vc_column_text][vc_column_text ct_style=&#8220;list-block&#8220; css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Wissen vereinheitlichen<\/h3>\n<p>Verbinden Sie alle Ihre Inhalte in einer einzigen, sicheren Wissensinfrastruktur. Vereinheitlichen Sie Informationssilos, damit Agenten, Kunden und KI-Assistenten sofort auf pr\u00e4zise, f\u00fcr sie zug\u00e4ngliche Informationen zugreifen k\u00f6nnen.[\/vc_column_text][vc_column_text ct_style=&#8220;list-block&#8220; css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Kontextbasierte Suchen unterst\u00fctzen<\/h3>\n<p>Semantische und kontextgesteuerte Suchen interpretieren, was Benutzer meinen, und nicht nur, was sie tippen, um Informationen in Echtzeit zur Verf\u00fcgung zu stellen. Dies sorgt f\u00fcr genaue, konsistente Antworten und reduziert die Bearbeitungszeit.[\/vc_column_text][vc_column_text ct_style=&#8220;list-block&#8220; css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">GenAI-Antworten erm\u00f6glichen<\/h3>\n<p>Verwenden Sie generative KI, um pr\u00e4gnante, transparente Antworten aus mehreren Quellen zusammenzustellen. Stellen Sie \u201eSmart Snippets\u201c mit klaren Zitaten zur Verf\u00fcgung, damit Benutzer den erhaltenen Informationen vertrauen und sie \u00fcberpr\u00fcfen k\u00f6nnen.[\/vc_column_text][vc_column_text ct_style=&#8220;list-block&#8220; css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Proaktive Empfehlungen geben<\/h3>\n<p>Knowledge Fabric unterst\u00fctzt virtuelle Agenten und Genesys Cloud\u2122 Virtual Agents mit kontextsensitiven Empfehlungen, Fehlerbehebung oder \u201eNext Actions\u201f basierend auf Live-Interaktionsdaten und Kontext.[\/vc_column_text][vc_column_text ct_style=&#8220;list-block&#8220; css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Erkenntnisse aus Wissen gewinnen<\/h3>\n<p>Gewinnen Sie automatisch Erkenntnisse dar\u00fcber, wie Wissen an jedem Interaktionspunkt verwendet wird. Erkennen Sie L\u00fccken, messen Sie die Effektivit\u00e4t und handeln Sie nach datengesteuerten Empfehlungen, um die Leistung zu verbessern.[\/vc_column_text][vc_column_text ct_style=&#8220;list-block&#8220; css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Wissen verantwortungsvoll verwalten<\/h3>\n<p>Pflegen Sie aktuelle, konforme Informationen \u00fcber Marken, Sprachen und Regionen hinweg mit integrierten Funktionen f\u00fcr Governance und die \u00dcberwachung des Datezustands, die pr\u00fcfen, ob Informationen aktuell, hochwertig und konsistent sind.[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/2&#8243; offset=&#8220;vc_col-sm-offset-1&#8243;][vc_single_image image=&#8220;611980&#8243; css=&#8220;&#8220; rounded_corners=&#8220;rounded-lg&#8220;][\/vc_column][\/vc_row][\/vc_section][vc_section flair=&#8220;%5B%7B%22hide_mobile%22%3A%22yes%22%7D%5D&#8220;][vc_row][vc_column]<div class=\"chunk-template-container\" ><div class=\"wpb-content-wrapper\"><p>[vc_section flair=&#8220;%5B%5D&#8220; css=&#8220;.vc_custom_1714506662607{background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8220;][vc_row][vc_column offset=&#8220;vc_col-md-offset-1 vc_col-md-10&#8243;]<a class=\"component-cta-block card w-100 h-100 bgc-lgray centered cta-text-end \"  href=\"\/de-de\/resources\/gartner-magic-quadrant-for-contact-center-as-a-service\" target=\"\" rel=\"\"><div class=\"row align-items-center image-stack-flipped card-body\"><div class=\"col-image col-md-5 flex-column justify-content-center img-top-container no-offset\"><img decoding=\"async\" width=\"474\" height=\"298\" class=\"rounded\" src=\"https:\/\/www.genesys.com\/media\/Gartner_MQ_Chunkers_2025.png\" alt=\"\" ><\/div><div class=\"col-content col-md-7 mt-1 mt-lg-0\"><div class=\"content-container\"><p><img decoding=\"async\" class=\"attachment-thumbnail size-thumbnail vc_single_image-img\" style=\"max-width: 175px;\" src=\"https:\/\/www.genesys.com\/media\/d6672569-gartnerlogo-gray.svg\" sizes=\"(max-width: 175px) 100vw, 175px\" srcset=\"https:\/\/www.genesys.com\/media\/d6672569-gartnerlogo-gray.svg 264w, https:\/\/www.genesys.com\/media\/d6672569-gartnerlogo-gray.svg 300w, https:\/\/www.genesys.com\/media\/d6672569-gartnerlogo-gray.svg 566w, https:\/\/www.genesys.com\/media\/d6672569-gartnerlogo-gray.svg 1244w\" alt=\"Gartner-Logo\" width=\"264\" height=\"61\" \/><\/p>\n<p>2025 Gartner\u00ae Magic Quadrant\u2122 for Contact Center as a Service<\/p>\n<p class=\"h5 text-balance\">Gartner nennt Genesys zum elften Mal in Folge als einen Leader<\/p>\n<\/div><div class=\" btn-container mt-2\"><div class=\"btn btn-primary\">Gartner-Bericht anfordern<\/div><\/div><\/div><\/div><\/a>[\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div><style type=\"text\/css\" data-type=\"vc_shortcodes-custom-css\">.vc_custom_1714506662607{background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}<\/style><\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section flair=&#8220;%5B%7B%22hide_mobile%22%3A%22yes%22%7D%5D&#8220;][vc_row content_placement=&#8220;middle&#8220;][vc_column width=&#8220;5\/12&#8243;][vc_column_text ct_style=&#8220;stat&#8220; css=&#8220;&#8220; ct_stat_link=&#8220;url:https%3A%2F%2Fwww.genesys.com%2Fde-de%2Fresources%2Fstate-of-cx&#8220;]<\/p>\n<h2 class=\"h1\">37\u00a0%<\/h2>\n<p class=\"text-24\">der Verbraucher sagen, dass sie einen sachkundigen Agenten in einer Service-Interaktion am meisten sch\u00e4tzen<\/p>\n<p>\u201eDer aktuelle Stand der Customer Experience\u201c,<br \/>\nGenesys, 2025[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/2&#8243; offset=&#8220;vc_col-sm-offset-1&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h2>Begeistern Sie Kunden und unterst\u00fctzen Sie Mitarbeiter mit automatisierten Antworten<\/h2>\n<p>Erhalten Sie Zugang zu benutzerfreundlichen Tools f\u00fcr die Suche nach und Verkn\u00fcpfung von Informationen und f\u00fcr die Beantwortung von Fragen. Beseitigen Sie Silos mit Collaboration-Tools, die Ihre Inhaltsbibliothek, Kundendaten und andere Ressourcen einfach zusammenstellen und darauf zugreifen k\u00f6nnen. Geben Sie Ihren Kunden und Mitarbeitern zum richtigen Zeitpunkt die richtigen Informationen an die Hand, um jede Kundeninteraktion zu verbessern.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section par_bg=&#8220;enable&#8220; background_color=&#8220;bgc-lgray&#8220; flair=&#8220;%5B%7B%22flair_type%22%3A%22f_type_image%22%2C%22hide_mobile%22%3A%22yes%22%7D%5D&#8220; el_class=&#8220;bg-cover bg-150-md bg-center bg-norepeat&#8220; css=&#8220;.vc_custom_1740963356468{background-image: url(https:\/\/www.genesys.com\/media\/capability-home-pill-background.png?id=542417) !important;}&#8220;][vc_row r_gutter_size=&#8220;gutter-small&#8220; background_color=&#8220;bgc-glass&#8220; equal_height=&#8220;yes&#8220; el_class=&#8220;py-3 px-1 px-lg-3 rounded mt-0&#8243;][vc_column width=&#8220;7\/12&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h2>Machen Sie Wissen zum Bindeglied Ihrer Kundenerfahrung<\/h2>\n<p>Geben Sie Kunden und Mitarbeitern Zugang zu einer einzigen intelligenten Wissensquelle, die jeden Kanal, jede Rolle und jede Region umfasst. Entwickeln Sie Ihr Unternehmenswissen weiter, damit jedes Team auf die gleichen vertrauensw\u00fcrdigen Informationen zugreift. Schlie\u00dfen Sie den Kreis mit kontinuierlichem Feedback, um die Genauigkeit von Self-Service-Optionen und die Effektivit\u00e4t der Agenten zu verbessern.[\/vc_column_text][\/vc_column][vc_column el_class=&#8220;mt-2&#8243;][vc_row_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Unternehmenswissen auf einer intelligenten Ebene<\/h3>\n<p>Bringen Sie vorhandene Inhalte aus CRM-Systemen, Wikis, Intranets und Legacy-Systemen zusammen. Unterst\u00fctzen Sie Sprach- und digitale Kan\u00e4le, um Konsistenz und Kontext \u00fcber jeden Touchpoint hinweg zu gew\u00e4hrleisten.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Wissen, das m\u00fchelos aktiviert und orchestriert werden kann<\/h3>\n<p>Setzen Sie Wissen dort ein, wo es bereits vorhanden ist, ohne Inhalte neu zu erstellen. Stellen Sie eine sichere Verbindung zu diesen Quellen her, interpretieren Sie den Kontext in Echtzeit und liefern Sie jedem Benutzer die relevanteste Antwort.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Automatisierte Informationsfl\u00fcsse f\u00fcr Echtzeiterlebnisse<\/h3>\n<p>Semantische Suchfunktionen, auf GenAI gest\u00fctzte Zusammenfassungen und KI-Empfehlungen liefern bei jeder Interaktion automatisch kontextrelevantes Wissen.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Ein Wissensportal f\u00fcr alle<\/h3>\n<p>Aktivieren Sie bestimmte Kategorien oder die gesamte Wissensdatenbank als Support-Center. F\u00fcgen Sie ganz einfach intelligente Suchfunktionen hinzu, einschlie\u00dflich eines Dropdown-Men\u00fcs mit \u201eTypeahead\u201f-Funktionalit\u00e4t, das Informationen schnell findet. [\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Wissen, das sich weltweit skalieren l\u00e4sst<\/h3>\n<p>Bieten Sie konsistente Erlebnisse in allen unterst\u00fctzten Sprachen durch ortsbezogene Indizierung und Spracherkennung. Stellen Sie sicher, dass Informationen in jedem Markt korrekt und kontextuell relevant bleiben.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h3 class=\"h5\">Datengest\u00fctzte Wissensoptimierung<\/h3>\n<p>Verwenden Sie Berichte \u00fcber Nutzung und Effektivit\u00e4t, um L\u00fccken proaktiv zu schlie\u00dfen. \u00dcberblicken Sie, welche Wissensanfragen erfolgreich waren und welche nicht, sowie die am h\u00e4ufigsten verwendeten Informationen.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section flair=&#8220;%5B%7B%22hide_mobile%22%3A%22yes%22%7D%5D&#8220;][vc_row el_class=&#8220;reset-mt&#8220;][vc_column width=&#8220;5\/12&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h2>Das sagen unsere Kunden<\/h2>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/2&#8243; offset=&#8220;vc_col-sm-offset-1&#8243;]<div class=\"btn-container justify-content-lg-end justify-content-end\"><a role=\"button\"  class=\"btn chevron btn-secondary\" href=\"\/de-de\/customer-stories\" target=\"\" rel=\"\">Alle Erfolgsgeschichten lesen<\/a><\/div>[\/vc_column][\/vc_row][vc_row el_class=&#8220;reset-mt&#8220;][vc_column]<div class=\"component-customer-carousel default-layout\" data-current-active=\"0\" data-layout=\"default\" data-count=\"2\"><div class=\"carousel-main-row\"><div class=\"carousel-logo-col\"><div class=\"logo-nav-item active\"><a class=\"logo-nav\" aria-label=\"View Western Sydney University story\" title=\"Western Sydney University\" href=\"#520675\"><img decoding=\"async\" class=\"company-logo\" alt=\"Wsu logo 300\" src=\"https:\/\/www.genesys.com\/media\/WSU_Logo_300.png\" width=\"300\" height=\"44\"><\/a><\/div><div class=\"logo-nav-item\"><a class=\"logo-nav\" aria-label=\"View Charles Sturt University story\" title=\"Charles Sturt University\" href=\"#607954\"><img decoding=\"async\" class=\"company-logo\" alt=\"Csu logo\" src=\"https:\/\/www.genesys.com\/media\/CharlesSturtUni_Logo_border-scaled.png\" width=\"1600\" height=\"462\"><\/a><\/div><\/div><div class=\"carousel-content-col\"><button aria-label=\"Previous panel\" title=\"Previous panel\" class=\"prev-control carousel-controls hidden\"><\/button><div class=\"customer-content active\" data-href=\"520675\" data-index=\"0\"><a class=\"content-row w-100 bgc-glass\" tabindex=\"-1\" href=\"https:\/\/www.genesys.com\/customer-stories\/western-sydney-university\"><div class=\"customer-image-col\"><img decoding=\"async\" class=\"header-image\" alt=\"Customer story video thumbnail wsu\" src=\"https:\/\/www.genesys.com\/media\/customer-story_video-thumbnail_WSU.jpg\" width=\"1216\" height=\"684\"><\/div><div class=\"customer-quote-col\"><p class=\"quote-content mb-2 quote-size-md\">\u201eDas \u00fcberw\u00e4ltigend positive Feedback von unseren Mitarbeitern im Contact Center unterstreicht den Erfolg der Transformation. Die Mitarbeiter loben die Zuverl\u00e4ssigkeit der Plattform, ihre Funktionalit\u00e4t und ihre F\u00e4higkeit, den Studierenden schnellere und eindeutigere Antworten zu geben.\u201c<\/p><p class=\"customer-name text-18 font-weight-bold mb-0\">\u2013 Scott Snyder<\/p><p class=\"customer-title\">Chief Information and Digital Officer, Western Sydney University<\/p><div class=\"btn-container\"><div class=\"btn btn-secondary small\">Kundenbericht lesen<\/div><\/div><\/div><\/a><\/div><div class=\"customer-content\" data-href=\"607954\" data-index=\"1\"><a class=\"content-row w-100 bgc-glass\" tabindex=\"-1\" href=\"https:\/\/www.genesys.com\/customer-stories\/charles-sturt-university\"><div class=\"customer-image-col\"><img decoding=\"async\" class=\"header-image\" alt=\"University students sitting in class using their laptops to take notes\" src=\"https:\/\/www.genesys.com\/media\/CSU-hero-image-2.png\" width=\"1088\" height=\"612\"><\/div><div class=\"customer-quote-col\"><p class=\"quote-content mb-2 quote-size-lg\">\u201eInnerhalb von zwei Wochen konnten wir unser Wissen in die Knowledge Workbench innerhalb der Genesys Cloud migrieren und unsere ersten digitalen Bots starten. Fast \u00fcber Nacht konnten wir eine Reduzierung unserer eingehenden Chat-Volumina um 20 % feststellen.\u201c<\/p><p class=\"customer-name text-18 font-weight-bold mb-0\">Paul Drake<\/p><p class=\"customer-title\">Contact Center Systems Manager, Charles Sturt University<\/p><div class=\"btn-container\"><div class=\"btn btn-secondary small\">Kundenbericht lesen<\/div><\/div><\/div><\/a><\/div><button aria-label=\"Next panel\" title=\"Next panel\" class=\"next-control carousel-controls\"><\/button><\/div><\/div><\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section flair=&#8220;%5B%7B%22hide_mobile%22%3A%22yes%22%7D%5D&#8220; css=&#8220;.vc_custom_1670964078417{padding-top: 4rem !important;padding-bottom: 8rem !important;}&#8220;][vc_row][vc_column width=&#8220;5\/12&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h2>Erfahren Sie, wie Genesys Sie noch unterst\u00fctzen kann<\/h2>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/2&#8243; offset=&#8220;vc_col-sm-offset-1&#8243;]<div class=\"btn-container justify-content-lg-end justify-content-end\"><a role=\"button\"  class=\"btn chevron btn-secondary\" href=\"\/de-de\/capabilities\" target=\"\" rel=\"\">Alle Funktionen anzeigen<\/a><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"capability-list icon-card-bg row gutter-small\"><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/co-browse-screenshare\"><div class=\"card-body\"><h3 class=\"h5\">Co-Browsing und Bildschirmfreigabe<\/h3><p>Sehen Sie in Echtzeit, warum sich Ihre Kunden an Sie wenden. Zeigen Sie ihnen, wie sie ihre Probleme l\u00f6sen k\u00f6nnen.<\/p><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/digital\"><div class=\"card-body\"><h3 class=\"h5\">Digitales Kundenengagement<\/h3><p>Unterst\u00fctzen Sie Ihre Teams mit einer umfassenden Suite von digitalen Funktionen\u00a0\u2013 oder mit Ihrer eigenen L\u00f6sung.<\/p><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/email-contact-center\"><div class=\"card-body\"><h3 class=\"h5\">E-Mail<\/h3><p>Erweitern Sie Ihr ServiceNow CSM-System um eine f\u00fchrende cloudbasierte Contact Center-L\u00f6sung mit leistungsstarker vorkonfigurierter Integration und heben Sie Ihre CX auf die n\u00e4chste Ebene.<\/p><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/live-chat-software\"><div class=\"card-body\"><h3 class=\"h5\">Live-Chat<\/h3><p>Chatten Sie mit Interessenten und Kunden in Echtzeit, um Probleme schnell zu l\u00f6sen\u00a0\u2013 kein Telefonanruf erforderlich.<\/p><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/messaging-apps\"><div class=\"card-body\"><h3 class=\"h5\">Messaging-Apps<\/h3><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/sms-messaging\"><div class=\"card-body\"><h3 class=\"h5\">SMS und Messaging<\/h3><p>Nutzen Sie bekannte mobile Kan\u00e4le, um mit Ihren Kunden in Kontakt zu treten, ohne ihren Tagesablauf zu unterbrechen.<\/p><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/social-media-customer-service\"><div class=\"card-body\"><h3 class=\"h5\">Social Media und Messaging-Apps<\/h3><p>Sprechen Sie Ihre Kunden auf beliebten Plattformen an, die sie bereits verwenden, darunter WhatsApp, Facebook und Instagram, und nutzen Sie Social Listening-Funktionen, um \u00f6ffentliche Gespr\u00e4che miteinzubeziehen.<\/p><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/virtual-agents\"><div class=\"card-body\"><h3 class=\"h5\">Virtueller Agent<\/h3><p>Verbessern Sie den Self-Service mit KI-gest\u00fctzten Chatbots, die den Kontext der Interaktion verstehen und wie menschliche Mitarbeiter agieren, um jederzeit eine herausragende Erfahrung zu bieten.<\/p><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/predictive-web-engagement\"><div class=\"card-body\"><h3 class=\"h5\">Vorausschauende Interaktion<\/h3><p>Nutzen Sie KI, um Online-Kunden im richtigen Moment proaktiv mit dem n\u00e4chstbesten Angebot oder der n\u00e4chstbesten Ressource zu binden.<\/p><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><div class=\"wpb_column col-12 col-md-6 col-xl-3 col-lg-4\"><a class=\"component card w-100 h-100 bgc-lgray vertical text-left nomedia mini\" href=\"https:\/\/www.genesys.com\/de-de\/capabilities\/work-automation-and-task-routing\"><div class=\"card-body\"><h3 class=\"h5\">Work Automation und Task Routing<\/h3><p>Nutzen Sie pr\u00e4zise, einheitliche Daten, um fundiertere Entscheidungen in Ihrem gesamten Back Office zu treffen.<\/p><\/div><div class=\"card-footer text-end\"><div class=\"btn-container justify-content-end\"><div class=\"btn small chevron btn-secondary only\" href=\"#\" target=\"\" rel=\"\"><\/div><\/div><\/div><\/a><\/div><\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section flair=&#8220;%5B%7B%22flair_type%22%3A%22f_type_image%22%7D%5D&#8220;][vc_row][vc_column width=&#8220;5\/12&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h2>Verbessern Sie Erfahrungen mit KI-basierten L\u00f6sungen<\/h2>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/2&#8243; offset=&#8220;vc_col-sm-offset-1&#8243;]<div class=\"btn-container justify-content-lg-end justify-content-end\"><a role=\"button\"  class=\"btn chevron btn-secondary\" href=\"\/de-de\/resources\" target=\"\" rel=\"\">Alle Ressourcen ansehen<\/a><\/div>[\/vc_column][\/vc_row][vc_row r_gutter_size=&#8220;gutter-small&#8220; equal_height=&#8220;yes&#8220;][vc_column]<div class=\"related-posts-container next-steps-module w-100\"><div class=\"inner-container scrollable-row-container\"><div class=\"row align-items-stretch gutter-small col-count-3 scrollable-row\"><div class=\"col-md-4 vertical-cards grid-item card-col item-image grid_type-resources\"><a class=\"card w-100 h-100 bgc-lgray component vertical text-start thumbnail chevron-only\" href=\"https:\/\/www.genesys.com\/de-de\/resources\/work-automation-and-task-routing\"><div class=\"thumbnail-col thubmnail\"><img decoding=\"async\" src=\"https:\/\/www.genesys.com\/media\/Work-automation-task-routing_DE.png\" height=\"697\" width=\"1351\" alt=\"Work automation &#038; task routing de\"><\/div><div class=\"card-body text-col\"><p class=\"assettag\">Product overview<\/p><h3 class=\"item-title h6\">Arbeitsautomatisierung und Aufgaben-Routing<\/h3><\/div><div class=\"card-footer text-end\"><div class=\"justify-content-end btn-container\"><div class=\"btn chevron small only btn-secondary\"><\/div><\/div><\/div><\/a><\/div><div class=\"col-md-4 vertical-cards grid-item card-col item-image grid_type-resources\"><a class=\"card w-100 h-100 bgc-lgray component vertical text-start thumbnail chevron-only\" href=\"https:\/\/www.genesys.com\/de-de\/resources\/state-of-cx\"><div class=\"thumbnail-col thubmnail\"><img decoding=\"async\" src=\"https:\/\/www.genesys.com\/media\/de_Resource-thumbnail_State-of-Customer-Experience-2025_1x.png\" height=\"464\" width=\"820\" alt=\"De resource thumbnail state of customer experience 2025 1x\"><\/div><div class=\"card-body text-col\"><p class=\"assettag\">Bericht<\/p><h3 class=\"item-title h6\">Der aktuelle Stand der Customer Experience<\/h3><\/div><div class=\"card-footer text-end\"><div class=\"justify-content-end btn-container\"><div class=\"btn chevron small only btn-secondary\"><\/div><\/div><\/div><\/a><\/div><div class=\"col-md-4 vertical-cards item-image grid-item card-col item-image grid_type-\"><a class=\"card w-100 h-100 bgc-lgray component vertical text-start thumbnail chevron-only\" href=\"https:\/\/appfoundry.genesys.com\/filter\/genesyscloud\/listing\/ff1b6df3-e0ac-44ac-909b-4cc1959823ca\"><div class=\"thumbnail-col thubmnail\"><img decoding=\"async\" src=\"https:\/\/www.genesys.com\/media\/resource-thumb-appfoundry-2024.png\" height=\"785\" width=\"1440\" alt=\"Resource thumb appfoundry 2024\"><\/div><div class=\"card-body text-col\"><h3 class=\"item-title h6\">Testen und kaufen: Work Automation<\/h3><\/div><div class=\"card-footer text-end\"><div class=\"justify-content-end btn-container\"><div class=\"btn chevron small only btn-secondary\"><\/div><\/div><\/div><\/a><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section sec_modern_width=&#8220;enable&#8220; background_color=&#8220;bgc-lgray&#8220; flair=&#8220;%5B%7B%22flair_type%22%3A%22f_type_image%22%2C%22hide_mobile%22%3A%22yes%22%7D%5D&#8220; css=&#8220;.vc_custom_1741334671940{background-image: url(https:\/\/www.genesys.com\/media\/Threads-Right-Wave.png?id=549945) !important;}&#8220; el_class=&#8220;px-0 py-2 px-md-5 py-md-5&#8243; el_id=&#8220;demo&#8220;][vc_row background_color=&#8220;bgc-glass&#8220; content_placement=&#8220;middle&#8220; el_class=&#8220;form-card&#8220;][vc_column width=&#8220;5\/12&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h2>Greifen Sie ganz einfach auf Ihre Wissensressourcen zu<\/h2>\n<p>Mit der richtigen Software f\u00fcr das Wissensmanagement k\u00f6nnen Sie jede Interaktion mit den richtigen Informationen unterst\u00fctzen. Bieten Sie Kunden einen schnelleren, effizienteren Self-Service und st\u00e4rken Sie Ihr Team. Sorgen Sie daf\u00fcr, dass Erkenntnisse klar und leicht zug\u00e4nglich sind, wenn sie am dringendsten gebraucht werden. Fordern Sie noch heute eine Demo an, um zu erfahren, wie Genesys automatisierte Antworten erm\u00f6glicht, auf die Sie sich verlassen k\u00f6nnen.[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/2&#8243; offset=&#8220;vc_col-sm-offset-1&#8243;]<div class=\"eloq_form elq-container gmkto_form_type_hot gmkto_format_vertical\"><form method=\"post\" name=\"MasterLeadIntakeForm\" action=\"https:\/\/s1260946616.t.eloqua.com\/e\/f2\" data-proc=\"inline\" data-ppcount=\"5\" onsubmit=\"return proc_submit(this);\" class=\"beam-form elq-form init no-bg-form yesknown yesprefill yespp strict-check\"  data-target=\".thank-you\" ><div id=\"known_person\" style=\"display:none;\"><p class=\"welcome_user\"><span id=\"welcome_person\">Willkommen zur\u00fcck<\/span> <span id=\"person_info\"><span class=\"person_first\"><\/span>&nbsp;<span class=\"person_last\"><\/span><\/span><\/p><p class=\"delete_button\"><a class=\"deletemyrecord\">Nicht du?<\/a><\/p><\/div><input value=\"MasterLeadIntakeForm\" type=\"hidden\" name=\"elqFormName\"><input value=\"1260946616\" type=\"hidden\" name=\"elqSiteId\"><input name=\"elqCampaignId\" type=\"hidden\"><input type=\"hidden\" name=\"elqCustomerGUID\" value=\"\"><input type=\"hidden\" name=\"elqCookieWrite\" value=\"0\"><input type=\"hidden\" name=\"client_ip_address\" id=\"fe449\" value=\"\"><div class=\"fields\"><input type=\"hidden\" name=\"CID\" id=\"fe198\" value=\"7010d000001KeaxAAC\"><input type=\"hidden\" name=\"CID_STATUS\" id=\"fe281\" value=\"\"><input type=\"hidden\" name=\"redirect_url\" id=\"fe217\" value=\"\"><input type=\"hidden\" name=\"landing_page_url\" id=\"fe204\" value=\"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/capabilities\/449924\"><input type=\"hidden\" name=\"post_type\" id=\"fe448\" value=\"capabilities\"><input type=\"hidden\" name=\"integration\" id=\"fe362\" value=\"\"><input type=\"hidden\" name=\"language_code\" id=\"fe479\" value=\"de-de\"><input type=\"hidden\" name=\"full_url\" id=\"fe983\" value=\"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/capabilities\/449924\"><input type=\"hidden\" name=\"post_id\" id=\"fe984\" value=\"485663\">\n    <div class=\"form-row row-email el_field form-floating\">\n        <input type=\"email\" class=\"form-control el_field elq-item-input required\" name=\"emailAddress\" id=\"fe192\" value=\"\" aria-label=\"Gesch\u00e4ftliche E-Mail\" placeholder=\"Gesch\u00e4ftliche E-Mail\">\n        <label for=\"fe192\">Gesch\u00e4ftliche E-Mail<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available el_field form-floating\">\n        <input type=\"text\" class=\"form-control el_field elq-item-input cb_available  required\" name=\"firstName\" id=\"fe190\" value=\"\" placeholder=\"Vorname\">\n        <label for=\"fe190\">Vorname<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available el_field form-floating\">\n        <input type=\"text\" class=\"form-control el_field elq-item-input cb_available required\" name=\"lastName\" id=\"fe191\" value=\"\" placeholder=\"Nachname\">\n        <label for=\"fe191\">Nachname<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row form-floating el_field\">\n        <input type=\"tel\" class=\"form-control el_field elq-item-input required pre-exclude\" name=\"busPhone\" id=\"fe215\" value=\"\" placeholder=\"Telefon\">\n        <label for=\"fe215\">Telefon<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe219\" name=\"jobLevel1\" data-value=\"\">\n            <option selected=\"\" value=\"\"><\/option><option value=\"C-Level\">Vorstand<\/option><option value=\"VP\">VP<\/option><option value=\"Director\">Director<\/option><option value=\"Manager\">Manager<\/option><option value=\"Principal\">Federf\u00fchrender Partner<\/option><option value=\"Engineer \/ Architect\">Ingenieur\/Architekt<\/option><option value=\"Consultant\">Berater<\/option><option value=\"Analyst\">Analyst<\/option><option value=\"Partner\">Partner<\/option><option value=\"Staff\">Mitarbeiter<\/option><option value=\"Unknown\">Unbekannt<\/option>\n        <\/select>\n        <label for=\"fe219\">Position<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe218\" name=\"jobFunction1\" data-value=\"\">\n            <option selected=\"\" value=\"\"><\/option>\n            <option value=\"Claims\">Forderungen<\/option><option value=\"Collections\">Forderungsmanagement<\/option><option value=\"Contact Center Management\">Contact Center-Management<\/option><option value=\"Customer Experience\">Customer\u00a0Experience<\/option><option value=\"Customer Service\">Kundenservice<\/option><option value=\"Ecommerce\/Digital Channels\">E-Commerce\/digitale Kan\u00e4le<\/option><option value=\"Finance\">Finanzen<\/option><option value=\"Human Resources\">Personalwesen<\/option><option value=\"Influencer\">Influencer<\/option><option value=\"Information Technology\">IT<\/option><option value=\"IT Architecture\">IT-Architektur<\/option><option value=\"IT Infrastructure\">IT-Infrastruktur<\/option><option value=\"IVR\">IVR<\/option><option value=\"Marketing\">Marketing<\/option><option value=\"Operations \/ Process Management\">Betriebs-\/Prozessmanagement<\/option><option value=\"Production Management\">Produktionsleitung<\/option><option value=\"Purchasing\">Kauf<\/option><option value=\"Sales\">Vertrieb<\/option><option value=\"Unknown\">Unbekannt<\/option>\n        <\/select>\n        <label for=\"fe218\">Anwendungsbereiche<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <input type=\"text\" class=\"form-control el_field elq-item-input cb_available required eloq_ppe\" name=\"company\" id=\"fe193\" value=\"\" placeholder=\"Unternehmensname\">\n        <label for=\"fe193\">Unternehmensname<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe194\" name=\"country\" data-value=\"\">\n            <option value=\"\"><\/option>\n            <!-- Add country options here -->\n        <\/select>\n        <label for=\"fe194\">Land<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available country_dep el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe214\" name=\"stateProv\" data-value=\"\">\n            <option selected=\"\" value=\"\"><\/option>\n        <\/select>\n        <label for=\"fe214\">State\/Province<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <input type=\"text\" class=\"form-control el_field elq-item-input cb_available required eloq_ppe\" name=\"website1\" id=\"fe801\" value=\"\" placeholder=\"Ihre Website\">\n        <label for=\"fe801\">Ihre Website<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <input type=\"text\" class=\"form-control el_field elq-item-input cb_available required eloq_ppe\" name=\"city\" id=\"fe226\" value=\"\" placeholder=\"Stadt\">\n        <label for=\"fe226\">Stadt<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <input type=\"text\" class=\"form-control el_field elq-item-input cb_available required eloq_ppe\" name=\"title\" id=\"fe220\" value=\"\" placeholder=\"Jobtitel\">\n        <label for=\"fe220\">Jobtitel<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe221\" name=\"industry1\" data-value=\"\">\n            <option value=\"\" ><\/option>\n            <option value=\"Banking\">Bankwesen<\/option><option value=\"Business Services\">Unternehmensdienstleistungen<\/option><option value=\"Capital Markets\">Capital Markets<\/option><option value=\"Communications\">Communications<\/option><option value=\"Consumer Products\">Consumer Products<\/option><option value=\"Defense & Intelligence\">Defense & Intelligence<\/option><option value=\"Education & Non-Profit\">Education & Non-Profit<\/option><option value=\"Energy & Utilities\">Energie- und Versorgungsunternehmen<\/option><option value=\"Entertainment\">Unterhaltungsbranche<\/option><option value=\"Government\">Beh\u00f6rden<\/option><option value=\"Insurance\">Versicherungen<\/option><option value=\"Life Sciences\">Life Sciences<\/option><option value=\"Logistics\">Logistics<\/option><option value=\"Manufacturing\">Manufacturing<\/option><option value=\"Payors\">Payors<\/option><option value=\"Providers\">Providers<\/option><option value=\"Retailers\">Retailers<\/option><option value=\"Technology\">Technologie<\/option><option value=\"Travel & Hospitality\">Travel & Hospitality<\/option><option value=\"Retail Banking\">Retail Banking<\/option><option value=\"Other\">Sonstige<\/option>\n        <\/select>\n        <label for=\"fe221\">Branche<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe222\" name=\"levelofInterest1\" data-value=\"\">\n            <option value=\"\"><\/option>\n            <option value=\"Just researching\">\u2026 informiere mich nur<\/option><option value=\"Gathering business requirements\">\u2026 recherchiere die Anforderungen<\/option><option value=\"Comparing solutions\">\u2026 vergleiche L\u00f6sungen<\/option><option value=\"Ready for a conversation\">\u2026 bin an einem Gespr\u00e4ch interessiert<\/option>\n        <\/select>\n        <label for=\"fe222\">Ich \u2026<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div>\n    <div class=\"form-row cb_available eloq_ppe el_field form-floating\">\n        <select class=\"form-select el_field elq-item-select cb_available required eloq_ppe\" id=\"fe225\" name=\"numberofAgentsForm1\" data-value=\"\">\n            <option value=\"\"><\/option>\n            <option value=\"1-20\">1-20<\/option><option value=\"21-50\">21\u201350<\/option><option value=\"51-100\">51\u2013100<\/option><option value=\"101-300\">101\u2013300<\/option><option value=\"301-500\">301\u2013500<\/option><option value=\"501-1000\">501\u20131000<\/option><option value=\">1000\">&gt;1000<\/option><option value=\"No Contact Center\">Kein Contact\u00a0Center<\/option><option value=\"Don't Know\">Ich wei\u00df es nicht<\/option>\n        <\/select>\n        <label for=\"fe225\">Anzahl der Arbeitspl\u00e4tze im Contact Center<span class=\"required-asterisk\">*<\/span><\/label>\n    <\/div><div class=\"form-check single-checkbox-row form-row gdpr-field white-box required\"><input type=\"checkbox\" class=\"el_field eloq_ppe\" name=\"explicitConsentEmailPhone\" id=\"fe224\" val=\"\"><label class=\"checkbox-aligned elq-item-label\" for=\"fe224\">Ja. Ich m\u00f6chte per E-Mail oder Telefon \u00fcber Neuigkeiten zu Genesys auf dem Laufenden gehalten werden.<\/label><\/div><div class=\"single-checkbox-row form-row white-box \"><input type=\"checkbox\" class=\"el_field eloq_ppe\" name=\"contactMe\" id=\"fe509\" val=\"\"><label class=\"checkbox-aligned elq-item-label\" for=\"fe509\">Ich h\u00e4tte es gern, dass mich jemand kontaktiert.<\/label><\/div><input type=\"hidden\" data-query=\"utm_medium\" name=\"utm_medium\" id=\"fe199\" value=\"\"><input type=\"hidden\" data-query=\"utm_source\" name=\"utm_source\" id=\"fe200\" value=\"\"><input type=\"hidden\" data-query=\"utm_campaign\" name=\"utm_campaign\" id=\"fe201\" value=\"\"><input type=\"hidden\" data-query=\"utm_term\" name=\"utm_term\" id=\"fe202\" value=\"\"><input type=\"hidden\" data-query=\"utm_content\" name=\"utm_content\" id=\"fe203\" value=\"\"><input type=\"hidden\" data-query=\"ost_tool\" name=\"ost_tool\" id=\"fe293\" value=\"\"><input type=\"hidden\" data-query=\"ost_campaign\" name=\"ost_campaign\" id=\"fe294\" value=\"\"><input type=\"hidden\" data-query=\"ost_content\" name=\"ost_content\" id=\"fe295\" value=\"\"><input type=\"hidden\" data-query=\"blaid\" name=\"eloquaBLAID_c\" id=\"fe3099\" value=\"\"><input type=\"hidden\" data-query=\"gclid\" name=\"gCLID1\" id=\"fe283\" value=\"\"><input type=\"hidden\" data-query=\"mkwid\" name=\"mKWID1\" id=\"fe678\" value=\"\"><input type=\"hidden\" name=\"gAClientID1\" id=\"fe284\" value=\"\"><input type=\"hidden\" name=\"noteCreatorTitle1\" id=\"fe313\" value=\"\"><input type=\"hidden\" name=\"webContentAutoResponderDefault\" id=\"fe286\" value=\"Hot Lead\"><input type=\"hidden\" name=\"webContentAutoResponderTitle\" id=\"fe287\" value=\"\"><input type=\"hidden\" name=\"webContentAutoResponderURL\" id=\"fe288\" value=\"\"><input type=\"hidden\" name=\"noteCreator2\" id=\"fe478\" value=\"\"><input type=\"hidden\" class=\"yesprefill\" name=\"neverbounceResult1\" id=\"fe640\" value=\"OFF\"><input type=\"hidden\" class=\"yesprefill\" name=\"neverbounceFlags1\" id=\"fe641\" value=\"OFF\"><input type=\"hidden\" class=\"yesprefill\" name=\"neverbounceSuggestedCorrection1\" id=\"fe642\" value=\"6sense\"><input type=\"hidden\" name=\"clearbitPersonID1\" id=\"fe630\" value=\"\"><input type=\"hidden\" name=\"clearbitFieldCount1\" id=\"fe633\" value=\"\"><input type=\"hidden\" name=\"clearbitTitle1\" id=\"fe646\" value=\"\"><input type=\"hidden\" name=\"clearbitRole1\" id=\"fe631\" value=\"\"><input type=\"hidden\" name=\"clearbitNumberofEmployees1\" id=\"fe647\" value=\"\"><input type=\"hidden\" name=\"clearbitNumberofEmployeesRange1\" id=\"fe648\" value=\"\"><input type=\"hidden\" name=\"clearbitWebsite1\" id=\"fe802\" value=\"\"><input type=\"hidden\" name=\"browserUserAgent\" id=\"fe3319\" value=\"\"><input type=\"text\" class=\"honeypp\" name=\"honeypp\" id=\"honeypp\" value=\"\" ><input role=\"button\" aria-label=\"Demo anfordern\" type=\"Submit\" class=\"submit-button-style btn btn-primary \" value=\"Demo anfordern\" id=\"fe195\"><div class=\"loading\"><\/div><div class=\"gdpr-field form-row white-box legal\"><span>Durch die Bereitstellung Ihrer Informationen erkl\u00e4ren Sie sich mit unseren <a href=\"https:\/\/www.genesys.com\/de-de\/company\/legal-docs\/datenschutzerklaerung\" target=\"_blank\">Datenschutzbestimmungen<\/a> einverstanden<\/span><\/div><\/div><\/form><\/div>[vc_column_text css=&#8220;&#8220; el_class=&#8220;thank-you&#8220;]<\/p>\n<p class=\"h4\">Vielen Dank f\u00fcr Ihr Interesse.<\/p>\n<p>Wir melden uns bei Ihnen, um einen f\u00fcr Sie passenden Termin zu vereinbaren.[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section][vc_row][vc_column width=&#8220;5\/12&#8243;][vc_column_text css=&#8220;&#8220;]<\/p>\n<h2>H\u00e4ufig gestellte Fragen zu Wissensmanagement-Tools<\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column offset=&#8220;vc_col-lg-offset-2 vc_col-lg-8 vc_col-md-offset-1 vc_col-md-10 vc_col-sm-offset-0&#8243;]<div class=\"component-accordion-container no-title\" data-display=\"accordion\"><div class=\"component-accordion-content custom-accordion\" data-opened=\"1\"><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Was sind Tools f\u00fcr das Wissensmanagement?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Tools f\u00fcr das Wissensmanagement helfen Unternehmen, Wissen aus verschiedenen Systemen zu erfassen, zu organisieren und anzuwenden. Dazu geh\u00f6ren Systeme zur Dokumentenverwaltung, Datenbanken, Intranets, Suchmaschinen, Plattformen f\u00fcr die Zusammenarbeit, KI-gest\u00fctzte Wissensdatenbanken und Lernmanagementsysteme.<\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Welche drei Technologien werden f\u00fcr das Wissensmanagement verwendet?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>F\u00fcr das Wissensmanagement werden drei Schl\u00fcsseltechnologien eingesetzt:<\/p>\n<ul>\n<li>K\u00fcnstliche Intelligenz (KI) zur Automatisierung der Erfassung und Kategorisierung von Wissen und zur Erstellung von Empfehlungen auf der Grundlage von Datenmustern.<\/li>\n<li>Collaboration-Tools, die den Austausch und die gemeinsame Erstellung von Wissen zwischen Teams erleichtern.<\/li>\n<li>Wissensdatenbanken zum Speichern und Organisieren von Wissen in einem durchsuchbaren Format f\u00fcr einfachen Zugriff.<\/li>\n<\/ul>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Wer sollte das Wissensmanagement nutzen?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Tools f\u00fcr das Wissensmanagement helfen Unternehmen jeder Gr\u00f6\u00dfe bei der gemeinsamen Nutzung von Prozessen, Praktiken, Informationen und Richtlinien. Das kann zwischen Abteilungen oder Gruppen und Funktionsbereichen erfolgen.<\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Aus welchen Komponenten besteht das Wissensmanagement?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Die Erstellung, Speicherung und gemeinsame Nutzung von Wissen geh\u00f6ren alle zu einem umfassenden Wissensmanagementprogramm. Mit einer zuverl\u00e4ssigen L\u00f6sung f\u00fcr das Wissensmanagement k\u00f6nnen Ersteller Wissen in verschiedenen Formaten, einschlie\u00dflich Text und Bildern, bereitstellen. Es muss gen\u00fcgend Speicherplatz vorhanden sein, um das gesamte Wissen, das ein Unternehmen ben\u00f6tigt, an einem Ort zu speichern. Au\u00dferdem m\u00fcssen verschiedene Arten der Wissensnutzung m\u00f6glich sein, einschlie\u00dflich verschiedener Berechtigungstypen und Nutzungskan\u00e4le.<\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Wie kann ich mit dem Wissensmanagement beginnen?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Best Practice erfordert eine Analyse des aktuellen Wissensstands in Ihrem Unternehmen. Stellen Sie sich die folgenden Fragen:<\/p>\n<ul>\n<li>Wie wird Wissen heutzutage verwaltet?<\/li>\n<li>Wer generiert Wissen?<\/li>\n<li>In wie vielen Tools speichern wir derzeit Wissen?<\/li>\n<li>Welche Arten von Wissensmanagement-Tools verwenden wir derzeit? Was werden unsere zuk\u00fcnftigen Anforderungen an ein Tool sein?<\/li>\n<li>Wer wird das Wissen nutzen? Wird das Wissen in Echtzeit ben\u00f6tigt?<\/li>\n<li>Wie kann das Wissen bearbeitet werden?<\/li>\n<li>Welche Berechtigungen ben\u00f6tigen wir f\u00fcr unsere Wissensautoren und -benutzer?<\/li>\n<\/ul>\n<p>Als N\u00e4chstes bestimmen Sie den idealen Wissensstand in Ihrem Unternehmen. In fast allen F\u00e4llen beruht der ideale Wissensaustausch auf einem zentralisierten System. Gut durch Administratoren \u00fcberwachtes Wissen gew\u00e4hrleistet Vollst\u00e4ndigkeit und Genauigkeit.<\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Welche Art von Wissen unterst\u00fctzt das Wissensmanagement?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Wenn der Informationsaustausch f\u00fcr Sie am wichtigsten ist, kann das Wissensmanagement eine Vielzahl von Medientypen unterst\u00fctzen. Text, Rich-Text, Bilder und Videos sind die wichtigsten Funktionen einer internen Wissensdatenbank.<\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Was sind die wichtigsten Aspekte eines erstklassigen Wissensmanagements?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Zentralisiertes Wissen erm\u00f6glicht eine effektivere Nutzung der IT. Alle Wissenskonsumenten sollten auf eine einzige Wissensdatenbank zugreifen, unabh\u00e4ngig davon, wie sie das Wissen nutzen. Eine einheitliche Wissensdatenbank, die das Wissen f\u00fcr alle Kan\u00e4le verf\u00fcgbar macht, erm\u00f6glicht konsistente und grundlegende Erkenntnisse. Alle Abteilungen und Gesch\u00e4ftsbereiche profitieren davon.<\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Was sind die wichtigsten gesch\u00e4ftlichen Vorteile der Verwendung zentralisierter Wissensmanagementsysteme?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Ein zentralisiertes Wissens-Repository bietet Ihnen eine Reihe von Vorteilen. Zum Beispiel:<\/p>\n<ul>\n<li>Zeitersparnis bei der Suche nach Informationen oder Hilfe bei Problemen mit der Versionskontrolle.<\/li>\n<li>Vereinfachter Zugang zum Wissen f\u00fcr Benutzer.<\/li>\n<li>Bessere KPIs f\u00fcr den Kundenservice, da die Mitarbeiter schneller auf das Wissen zugreifen k\u00f6nnen, das sie f\u00fcr die Kundenbetreuung ben\u00f6tigen.<\/li>\n<\/ul>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Wie verbessert KI Ihre Wissensmanagement-Tools?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>KI kann Ihre Wissensmanagement-Tools durch die Einf\u00fchrung fortschrittlicher Funktionen wie der Automatisierung von Antworten und der verbesserten Abfrage von Informationen erheblich verbessern. Tools f\u00fcr das Wissensmanagement sind darauf ausgelegt, Informationen effizient zu organisieren, zu speichern und abzurufen. Durch die Integration von KI wird dies jedoch auf die n\u00e4chste Ebene gehoben.<\/p>\n<p>Mit KI-gest\u00fctzter Antwortautomatisierung k\u00f6nnen diese Tools automatisch Antworten auf h\u00e4ufig gestellte Fragen generieren, indem sie relevante Informationen aus einer umfangreichen Wissensdatenbank abrufen. Dadurch wird der Zeitaufwand f\u00fcr die Suche nach Antworten reduziert und sichergestellt, dass Mitarbeiter schnell korrekte und konsistente Informationen erhalten. KI kann Muster in Abfragen identifizieren und kontextrelevante Antworten liefern, was sowohl die Geschwindigkeit als auch die Genauigkeit verbessert.<\/p>\n<p>Dar\u00fcber hinaus verbessert KI die Gesamtfunktionalit\u00e4t von Wissensmanagement-Tools, indem sie aus Benutzerinteraktionen lernt. Auf Basis fr\u00fcherer Suchanfragen kann sie verwandte Artikel, Dokumente oder Daten empfehlen und gew\u00e4hrleisten, dass die Benutzer Zugang zu den relevantesten Informationen erhalten. KI kann auch dabei helfen, die Wissensdatenbank zu kuratieren und zu aktualisieren, veraltete Informationen zu identifizieren und neue Inhalte vorzuschlagen, um die Wissensdatenbank auf dem neuesten Stand zu halten.<\/p>\n<p>KI optimiert nicht nur die Effizienz von Wissensmanagement-Tools durch die Automatisierung von Antworten, sondern stellt auch sicher, dass die bereitgestellten Informationen korrekt, relevant und aktuell sind, wodurch die Gesamtproduktivit\u00e4t Ihres Unternehmens gesteigert wird.<\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Wie wirkt sich das Wissensmanagement f\u00fcr Call Center auf das Experience Management aus?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Das Wissensmanagement in Call Centern spielt eine entscheidende Rolle bei der Verbesserung des Experience Managements, indem es die Qualit\u00e4t der Kundeninteraktionen und die allgemeine Zufriedenheit direkt beeinflusst.<\/p>\n<p>Ein effektives Wissensmanagement stellt sicher, dass Call-Center-Agenten schnellen Zugriff auf genaue und aktuelle Informationen haben, sodass sie effizient und konsistent auf Kundenanfragen reagieren k\u00f6nnen. Wenn Agenten die richtigen Informationen schnell und einfach abrufen k\u00f6nnen, verk\u00fcrzt dies die Reaktionszeiten und erh\u00f6ht die Genauigkeit des bereitgestellten Supports, was sich direkt auf das Kundenerlebnis auswirkt.<\/p>\n<p>Durch die Rationalisierung des Informationsflusses minimiert das Wissensmanagement die Wahrscheinlichkeit von Fehlern oder Inkonsistenzen bei Kundeninteraktionen, was zu einer nahtloseren und positiveren Erfahrung f\u00fchrt. Dies wiederum verbessert das Experience Management, indem sichergestellt wird, dass die Kundeninteraktionen nicht nur effizient sind, sondern auch einen nachhaltigen positiven Eindruck hinterlassen.<\/p>\n<p>Dar\u00fcber hinaus integrieren Wissensmanagement-Tools h\u00e4ufig Feedbackschleifen, in denen Informationen aus Kundeninteraktionen in das System zur\u00fcckgef\u00fchrt werden. So kann das Unternehmen seine Wissensbasis kontinuierlich aktualisieren und verfeinern, um sicherzustellen, dass zuk\u00fcnftige Interaktionen auf historischen Erfahrungen basieren. Infolgedessen profitiert das Erfahrungsmanagement von diesem kontinuierlichen Verbesserungsprozess, der zu einem pers\u00f6nlicheren und effektiveren Kundenservice f\u00fchrt.<\/p>\n<p>Zusammenfassend l\u00e4sst sich sagen, dass ein robustes Wissensmanagement in Call Centern das Erlebnismanagement erheblich verbessert, indem sichergestellt wird, dass die Agenten gut ausgestattet sind, um Kunden zeitnah, genau und personalisiert zu unterst\u00fctzen.<\/p>\n<\/div><\/div><\/div><div class=\"row-100 content-item component-accordion-item\" ><div class=\"title-row\"><h3 class=\"component-accordion-title title h5\">Wie w\u00e4hle ich die richtige Wissensmanagement-Software f\u00fcr mein Unternehmen aus?<\/h3><i class=\"fa-kit ms-auto fa-chevron-down\"><\/i><\/div><div class=\"component-accordion-content content-row\"><div class=\"content-details\"><p>Die Wahl der richtigen Wissensmanagement-Software beginnt mit der Identifizierung Ihrer gr\u00f6\u00dften Herausforderungen. Entscheiden Sie, ob Sie Hilfe bei der Organisation von Dokumenten, der Erfassung von Expertenwissen, der Verbesserung der Zusammenarbeit oder der Unterst\u00fctzung des Kundenservice ben\u00f6tigen. Suchen Sie von dort aus nach Tools, die sich leicht in die bereits verwendeten Systeme integrieren lassen, damit Ihr Team die Funktionsweise nicht \u00e4ndern muss.<\/p>\n<p>Bewerten Sie Funktionen wie Suchgenauigkeit, Content-Tagging, Versionskontrolle und Zugriffsberechtigungen. Eine gute Plattform sollte die Identifizierung und Aktualisierung von Informationen vereinfachen. Stellen Sie sicher, dass Sie die Benutzerfreundlichkeit testen \u2013 Ihr Team verwendet eher ein Tool, das sich einfach und intuitiv anf\u00fchlt.<\/p>\n<p>Vergleichen Sie abschlie\u00dfend die Preise, Sicherheitsstandards und den Kundensupport. W\u00e4hlen Sie eine L\u00f6sung, die mit Ihrem Unternehmen wachsen und mit zunehmenden Mengen an Inhalten umgehen kann, ohne langsamer zu werden.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div>[\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_section background_color=&#8220;bgc-lgray&#8220; flair=&#8220;%5B%7B%22flair_type%22%3A%22f_type_image%22%2C%22hide_mobile%22%3A%22yes%22%7D%5D&#8220; css=&#8220;.vc_custom_1762451883407{background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8220;][vc_row content_placement=&#8220;middle&#8220; el_class=&#8220;no-shadow&#8220;][vc_column][\/vc_column][vc_column width=&#8220;5\/12&#8243; el_class=&#8220;order-md-1 order-5&#8243;][vc_column_text css=&#8220;&#8220;] Genesys Cloud Knowledge Fabric Vereinheitlichen Sie Unternehmenswissen in einer adaptiven Fabric, die agentische KI unterst\u00fctzt und die besten Antworten auf jede Frage liefert. [\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/2&#8243; offset=&#8220;vc_col-sm-offset-1&#8243;][vc_single_image image=&#8220;611981&#8243; css=&#8220;&#8220; rounded_corners=&#8220;rounded-lg&#8220;][\/vc_column][\/vc_row][\/vc_section][vc_section][vc_row][vc_column width=&#8220;5\/12&#8243;][vc_column_text css=&#8220;&#8220;] Smartes, vernetztes Wissensmanagement Bauen Sie ein umfassendes Informations\u00f6kosystem [&hellip;]<\/p>\n","protected":false},"author":1062,"featured_media":0,"template":"","tax_cap_lobby":[18115,18118],"tax_priority":[],"tax_contenttheme":[],"tax_bundle":[],"tax_contenttheme2":[],"tax_capability_sitewide":[],"tax_products_programs":[],"tax_buying_job":[],"tax_buyer_persona":[],"tax_sector":[],"tax_segment":[],"class_list":["post-449924","capabilities","type-capabilities","status-publish","hentry","tax_cap_lobby-ai-and-automation-de-de","tax_cap_lobby-digital-de-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/capabilities\/449924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/capabilities"}],"about":[{"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/types\/capabilities"}],"author":[{"embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/users\/1062"}],"version-history":[{"count":15,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/capabilities\/449924\/revisions"}],"predecessor-version":[{"id":614123,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/capabilities\/449924\/revisions\/614123"}],"wp:attachment":[{"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/media?parent=449924"}],"wp:term":[{"taxonomy":"tax_cap_lobby","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_cap_lobby?post=449924"},{"taxonomy":"tax_priority","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_priority?post=449924"},{"taxonomy":"tax_contenttheme","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_contenttheme?post=449924"},{"taxonomy":"tax_bundle","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_bundle?post=449924"},{"taxonomy":"tax_contenttheme2","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_contenttheme2?post=449924"},{"taxonomy":"tax_capability_sitewide","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_capability_sitewide?post=449924"},{"taxonomy":"tax_products_programs","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_products_programs?post=449924"},{"taxonomy":"tax_buying_job","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_buying_job?post=449924"},{"taxonomy":"tax_buyer_persona","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_buyer_persona?post=449924"},{"taxonomy":"tax_sector","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_sector?post=449924"},{"taxonomy":"tax_segment","embeddable":true,"href":"https:\/\/www.genesys.com\/de-de\/wp-json\/wp\/v2\/tax_segment?post=449924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}